{"id":177981,"date":"2025-04-18T13:19:11","date_gmt":"2025-04-18T11:19:11","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/il-campanone\/"},"modified":"2025-04-18T14:43:48","modified_gmt":"2025-04-18T12:43:48","slug":"il-campanone","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/","title":{"rendered":"IL CAMPANONE"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":158112,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177981","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"IL CAMPANONE","hero_text":"<p>D\u00e9licieux appartement au c\u0153ur de Citt\u00e0 Alta<\/p>\n<p>&#13;<\/p>\n<p>\u00a0<\/p>\n","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Appartement spacieux au c\u0153ur de la Citt\u00e0 Alta, avec une chambre et un grand s\u00e9jour, \u00e0 quelques pas de toutes les principales attractions du centre historique.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"<p>Parking priv\u00e9 disponible moyennant un suppl\u00e9ment en dehors de l&#8217;\u00e9tablissement.<\/p>\n","restaurant":"","breakfast":"","internet":"<p>WiFi disponible dans toute la structure.<\/p>\n","children":"","pets":"","latitude":"45.694254","longitude":"9.670685","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"MARCELLO SALA","registered_office":"","iu_addr_streetnumber":"Vicolo Ghiacciaia 8","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3934922959","iu_cell":"+39 3934922959","iu_website":"http:\/\/www.soeasyagency.com","iu_email":"ilcampanonebergamo@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"4","id_madeep":"","id_visit_manza":"11102","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"slides":[{"image":{"ID":158112,"id":158112,"title":"5d281589c17d80ca88812f8050435413_30327a73.jpg","filename":"5d281589c17d80ca88812f8050435413_30327a73.jpg","filesize":317178,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/5d281589c17d80ca88812f8050435413_30327a73-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5d281589c17d80ca88812f8050435413_30327a73-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:18:54","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d281589c17d80ca88812f8050435413_30327a73.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158119,"id":158119,"title":"85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","filename":"85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","filesize":601011,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"85389535a8354e8bcc0e6a8c514d5597_6735c6b9-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:18:55","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85389535a8354e8bcc0e6a8c514d5597_6735c6b9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158126,"id":158126,"title":"35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","filename":"35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","filesize":487971,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/35131d90d98308356521c386ce3ee095_b64c8f6a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"35131d90d98308356521c386ce3ee095_b64c8f6a-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:18:57","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/35131d90d98308356521c386ce3ee095_b64c8f6a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158133,"id":158133,"title":"bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","filename":"bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","filesize":392994,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:18:58","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd43a157d9dabe7d6d9c7103e52b1f84_9c7e466e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158140,"id":158140,"title":"1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","filename":"1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","filesize":396389,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/1b0579cf7b56934b6bf030706696e37d_9278b282-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1b0579cf7b56934b6bf030706696e37d_9278b282-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:18:59","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1b0579cf7b56934b6bf030706696e37d_9278b282.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158147,"id":158147,"title":"d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","filename":"d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","filesize":367184,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/d7c6aa390144d894ae33c15d1248edd9_e25c4472-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d7c6aa390144d894ae33c15d1248edd9_e25c4472-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:00","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7c6aa390144d894ae33c15d1248edd9_e25c4472.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158154,"id":158154,"title":"176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","filename":"176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","filesize":381684,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:02","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/176fe0e58e2b39b3ef532266ee5f70c8_4d8540d2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158161,"id":158161,"title":"dd846312daea04ab594dfe7133637642_2fdc4713.jpg","filename":"dd846312daea04ab594dfe7133637642_2fdc4713.jpg","filesize":374175,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/dd846312daea04ab594dfe7133637642_2fdc4713-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"dd846312daea04ab594dfe7133637642_2fdc4713-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:03","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd846312daea04ab594dfe7133637642_2fdc4713.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158168,"id":158168,"title":"9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","filename":"9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","filesize":287383,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:04","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9f00471bbb88b9591a9b0d8138aa3c8e_bdf3ab2c.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158175,"id":158175,"title":"9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","filename":"9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","filesize":422111,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/9306f81bdc85bff7221711ee7247804c_d40ee301-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9306f81bdc85bff7221711ee7247804c_d40ee301-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:05","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9306f81bdc85bff7221711ee7247804c_d40ee301.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158182,"id":158182,"title":"beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","filename":"beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","filesize":384967,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/beda9dac4339f133d382fb3b95728a19_02d646fd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"beda9dac4339f133d382fb3b95728a19_02d646fd-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:07","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/beda9dac4339f133d382fb3b95728a19_02d646fd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158189,"id":158189,"title":"b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","filename":"b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","filesize":259475,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:08","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b38357e9c9a3b9e4b8bb672d97f48ecd_014af031.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158196,"id":158196,"title":"84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","filename":"84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","filesize":548755,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/il-campanone\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"84580fc909f2d4778075b54d2f4ea64b_e0d993e9-jpg-2","status":"inherit","uploaded_to":177981,"date":"2025-04-17 15:19:09","modified":"2025-04-18 12:43:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/84580fc909f2d4778075b54d2f4ea64b_e0d993e9.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"time":"<p>Check in dalle 15.00 alle 21.00&#13;<br \/>\nCheck out alle 10.00&#13;<br \/>\nLATE CHECK OUT :\u00a0&#13;<br \/>\ndopo le 21.00 extra cost di 10\u20ac&#13;<br \/>\ndopo le 22.30 extra cost di 20\u20ac&#13;<br \/>\ndopo 00.00 extra cost di 30\u20ac<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/158112"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177981"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177981"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177981"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177981"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}