{"id":178178,"date":"2025-04-18T13:24:39","date_gmt":"2025-04-18T11:24:39","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/libiscus-e-il-mare\/"},"modified":"2025-04-18T14:50:48","modified_gmt":"2025-04-18T12:50:48","slug":"libiscus-e-il-mare","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/","title":{"rendered":"L&#8217;IBISCUS E IL MARE"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":163358,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-178178","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"L'IBISCUS E IL MARE","hero_text":"<p lang='fr-FR'><span style='font-family: Verdana, serif;'><span>L&#8217;endroit id\u00e9al pour un s\u00e9jour inoubliable \u00e0 Bergame.<\/span><\/span><\/p>\n","slides":[{"image":{"ID":163358,"id":163358,"title":"80d5f4a16fd7773e2acaad8e90b66953_b613ecff","filename":"80d5f4a16fd7773e2acaad8e90b66953_b613ecff.jpg","filesize":258125,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff-2\/","alt":"","author":"0","description":"","caption":"","name":"80d5f4a16fd7773e2acaad8e90b66953_b613ecff-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:18","modified":"2025-04-18 12:50:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80d5f4a16fd7773e2acaad8e90b66953_b613ecff.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163365,"id":163365,"title":"b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e","filename":"b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e.jpg","filesize":362177,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-2\/","alt":"","author":"0","description":"","caption":"","name":"b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:19","modified":"2025-04-18 12:50:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2000,"height":1500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e.jpg","2048x2048-width":2000,"2048x2048-height":1500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b2dbb293b0f8c13336a63e7c7371c257_4fc75d7e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163372,"id":163372,"title":"195809e559251a58e9e802b6bceb572d_daa560d3","filename":"195809e559251a58e9e802b6bceb572d_daa560d3.jpg","filesize":227288,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/195809e559251a58e9e802b6bceb572d_daa560d3-2\/","alt":"","author":"0","description":"","caption":"","name":"195809e559251a58e9e802b6bceb572d_daa560d3-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:20","modified":"2025-04-18 12:50:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/195809e559251a58e9e802b6bceb572d_daa560d3.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163379,"id":163379,"title":"3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44","filename":"3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44.jpg","filesize":232729,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-2\/","alt":"","author":"0","description":"","caption":"","name":"3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:21","modified":"2025-04-18 12:50:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3bbdf299b07869e7eae0a58ccd4d9d25_dec4bf44.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163386,"id":163386,"title":"0f71cb1cad72b896034431280c8fd753_3ccc1a6c","filename":"0f71cb1cad72b896034431280c8fd753_3ccc1a6c.jpg","filesize":245779,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c-2\/","alt":"","author":"0","description":"","caption":"","name":"0f71cb1cad72b896034431280c8fd753_3ccc1a6c-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:22","modified":"2025-04-18 12:50:50","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f71cb1cad72b896034431280c8fd753_3ccc1a6c.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163393,"id":163393,"title":"b4e29724bfb1a6260d9e38b43465c594_bebe2195","filename":"b4e29724bfb1a6260d9e38b43465c594_bebe2195.jpg","filesize":213672,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/b4e29724bfb1a6260d9e38b43465c594_bebe2195-2\/","alt":"","author":"0","description":"","caption":"","name":"b4e29724bfb1a6260d9e38b43465c594_bebe2195-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:24","modified":"2025-04-18 12:50:51","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b4e29724bfb1a6260d9e38b43465c594_bebe2195.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163400,"id":163400,"title":"76dfcc008c7fcdfa4b4396fbed840a87_a79ea255","filename":"76dfcc008c7fcdfa4b4396fbed840a87_a79ea255.jpg","filesize":394728,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-2\/","alt":"","author":"0","description":"","caption":"","name":"76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:25","modified":"2025-04-18 12:50:51","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1366,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-768x1151.jpg","medium_large-width":768,"medium_large-height":1151,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255-1025x1536.jpg","1536x1536-width":1025,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255.jpg","2048x2048-width":1366,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/76dfcc008c7fcdfa4b4396fbed840a87_a79ea255.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163407,"id":163407,"title":"b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d","filename":"b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d.jpg","filesize":162725,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-2\/","alt":"","author":"0","description":"","caption":"","name":"b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:26","modified":"2025-04-18 12:50:51","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5897ed6b1a3b2bb96faf5abef45e93d_a379f65d.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163414,"id":163414,"title":"2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a","filename":"2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-scaled.jpg","filesize":630336,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/libiscus-e-il-mare\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-2\/","alt":"","author":"0","description":"","caption":"","name":"2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-2","status":"inherit","uploaded_to":178178,"date":"2025-04-18 08:42:27","modified":"2025-04-18 12:50:51","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1593,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-187x300.jpg","medium-width":187,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-768x1234.jpg","medium_large-width":768,"medium_large-height":1234,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-637x1024.jpg","large-width":637,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-956x1536.jpg","1536x1536-width":956,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-1275x2048.jpg","2048x2048-width":1275,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-scaled.jpg","gform-image-choice-sm-width":187,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-scaled.jpg","gform-image-choice-md-width":249,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b6c2b97554206b4e9d3c3ba4cae1bd2_1f8ef73a-scaled.jpg","gform-image-choice-lg-width":373,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>L&#8217;hibiscus est un symbole d&#8217;accueil. Pour nous, il repr\u00e9sente \u00e9galement un lien fort avec notre r\u00e9gion d&#8217;origine, la Sicile. &#8216;L&#8217;ibiscus e il mare&#8217; est un endroit accueillant o\u00f9 vous vous sentirez comme chez vous. L&#8217;appartement est bien meubl\u00e9, dans une position EXCELLENTE pour atteindre \u00e0 pied la partie historique de la ville (haute et basse) ; il est \u00e9galement reli\u00e9 \u00e0 l&#8217;a\u00e9roport d&#8217;Orio al Serio et \u00e0 la gare de Bergame par plusieurs bus. Les pubs, magasins, bars et supermarch\u00e9s situ\u00e9s \u00e0 proximit\u00e9 r\u00e9pondent aux besoins de tous les voyageurs.&#13;<br \/>\nL&#8217;appartement de 60 m\u00b2 r\u00e9cemment r\u00e9nov\u00e9 est situ\u00e9 au premier \u00e9tage et est accessible sans ascenseur. Il dispose d&#8217;une cuisine enti\u00e8rement \u00e9quip\u00e9e, d&#8217;un espace de d\u00e9tente avec un grand canap\u00e9 (qui se transforme en un confortable lit double si n\u00e9cessaire) et d&#8217;une t\u00e9l\u00e9vision de 43 pouces avec des cha\u00eenes de streaming (Netflix, Prime Video, Eurosport, Tennis TV). La salle de bains comporte une douche spacieuse et est \u00e9quip\u00e9e d&#8217;articles de toilette. Dans la chambre, il y a un grand lit double et une grande armoire.<\/p>\n","indepth":"<p>&#8216;L&#8217;ibiscus e il mare&#8217; est situ\u00e9 dans une position CENTRALE, \u00e0 5 minutes \u00e0 pied de l&#8217;Accademia Carrara et de la GAMEC et \u00e0 10 minutes \u00e0 pied du th\u00e9\u00e2tre Donizetti ; il est \u00e9galement possible de se rendre \u00e0 pied \u00e0 la Piazza Vecchia (environ 20 minutes), en se promenant le long des remparts v\u00e9nitiens (patrimoine de l&#8217;UNESCO), observant ainsi un merveilleux panorama.Le funiculaire (\u00e0 seulement 7 minutes de marche) qui relie la partie basse et la partie haute de la ville est pittoresque.\u00c0 proximit\u00e9, vous trouverez des pubs, des restaurants, des magasins et des supermarch\u00e9s tels que le Carrefour de Via Tasso (9 minutes de marche) et le Pam de Via Camozzi (8 minutes de marche).&#8217;L&#8217;ibiscus e il mare&#8217; est le lieu id\u00e9al pour en couple, en famille ou entre amis.C&#8217;est un endroit o\u00f9 vous vous sentirez bien accueillis, quel que soit votre pays d&#8217;origine, vos croyances religieuses ou la personne que vous aimez.<\/p>\n","howtogetthere":"<p>L\u2019\u00e9tablissement est situ\u00e9 en face du Palazzo Agliardi, dans la Via Pignolo. Depuis l&#8217;a\u00e9roport, vous pouvez prendre le bus 1 et descendre \u00e0 l&#8217;arr\u00eat Sant&#8217;Agostino ; de l\u00e0, vous pouvez marcher environ 400 m jusqu&#8217;\u00e0 votre destination. Un service de navette depuis et vers l&#8217;a\u00e9roport est disponible sur demande.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"<p>Non admis<\/p>\n","latitude":"45.701098","longitude":"9.673332","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"PAGANO ANGIOLO","registered_office":"Via Daste e Spalenga 45 Bergamo","iu_addr_streetnumber":"Via Pignolo, 79","iu_addr_postalcode":"24121","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"3389974025","iu_website":"","iu_email":"libiscuseilmare@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"4","id_madeep":"","id_visit_manza":"10124","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Check-in dopo le ore 15.00&#13;<br \/>\nCheck-out entro le ore 11.00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/178178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/178178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/163358"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=178178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=178178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=178178"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=178178"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=178178"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=178178"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=178178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}