{"id":178422,"date":"2025-04-18T13:31:46","date_gmt":"2025-04-18T11:31:46","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/life-hotel\/"},"modified":"2025-04-18T15:00:35","modified_gmt":"2025-04-18T13:00:35","slug":"life-hotel","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/","title":{"rendered":"LIFE HOTEL"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":169448,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-178422","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"LIFE HOTEL","hero_text":"","slides":[{"image":{"ID":169448,"id":169448,"title":"e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a","filename":"e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","filesize":477701,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-2\/","alt":"","author":"0","description":"","caption":"","name":"e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:33","modified":"2025-04-18 13:00:37","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169455,"id":169455,"title":"2184c2ca60179164b41b72ea8269beaa_c62b3c75","filename":"2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","filesize":125032,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-2\/","alt":"","author":"0","description":"","caption":"","name":"2184c2ca60179164b41b72ea8269beaa_c62b3c75-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:35","modified":"2025-04-18 13:00:37","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":667,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","large-width":1000,"large-height":667,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","1536x1536-width":1000,"1536x1536-height":667,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","2048x2048-width":1000,"2048x2048-height":667,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169462,"id":169462,"title":"23dfbb15fc3990a40c0107c909aac0f5_241be0fd","filename":"23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","filesize":125696,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-2\/","alt":"","author":"0","description":"","caption":"","name":"23dfbb15fc3990a40c0107c909aac0f5_241be0fd-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:36","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":667,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","large-width":1000,"large-height":667,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","1536x1536-width":1000,"1536x1536-height":667,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","2048x2048-width":1000,"2048x2048-height":667,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169469,"id":169469,"title":"f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310","filename":"f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","filesize":96617,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-2\/","alt":"","author":"0","description":"","caption":"","name":"f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:37","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":667,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","large-width":1000,"large-height":667,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","1536x1536-width":1000,"1536x1536-height":667,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","2048x2048-width":1000,"2048x2048-height":667,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169476,"id":169476,"title":"3084b00a752fc069f77371521a0b235f_2d1982c4","filename":"3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","filesize":97509,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/3084b00a752fc069f77371521a0b235f_2d1982c4-2\/","alt":"","author":"0","description":"","caption":"","name":"3084b00a752fc069f77371521a0b235f_2d1982c4-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:37","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169483,"id":169483,"title":"dfe098cca3166e98967f2433428601d3_57554850","filename":"dfe098cca3166e98967f2433428601d3_57554850.jpg","filesize":100341,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/dfe098cca3166e98967f2433428601d3_57554850-2\/","alt":"","author":"0","description":"","caption":"","name":"dfe098cca3166e98967f2433428601d3_57554850-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:38","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169490,"id":169490,"title":"6f3d4df145a440ae61beed14c5099ffe_32e41977","filename":"6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","filesize":370298,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/6f3d4df145a440ae61beed14c5099ffe_32e41977-2\/","alt":"","author":"0","description":"","caption":"","name":"6f3d4df145a440ae61beed14c5099ffe_32e41977-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:39","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169497,"id":169497,"title":"00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2","filename":"00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","filesize":107234,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-2\/","alt":"","author":"0","description":"","caption":"","name":"00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:40","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169504,"id":169504,"title":"7e73c88faf58710af309bc4abb37524f_6a172f37","filename":"7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","filesize":99549,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/7e73c88faf58710af309bc4abb37524f_6a172f37-2\/","alt":"","author":"0","description":"","caption":"","name":"7e73c88faf58710af309bc4abb37524f_6a172f37-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:41","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169511,"id":169511,"title":"3be66e1e8b99e626c58453a1a3b14719_ebe8d495","filename":"3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","filesize":437229,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-2\/","alt":"","author":"0","description":"","caption":"","name":"3be66e1e8b99e626c58453a1a3b14719_ebe8d495-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:42","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1364,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-1536x1023.jpg","1536x1536-width":1536,"1536x1536-height":1023,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","2048x2048-width":2048,"2048x2048-height":1364,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169518,"id":169518,"title":"01da58f1f39bcac4398bd5bbd575134a_56333e0f","filename":"01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","filesize":403219,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-2\/","alt":"","author":"0","description":"","caption":"","name":"01da58f1f39bcac4398bd5bbd575134a_56333e0f-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:43","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169525,"id":169525,"title":"56f120473cece6a6e2167b36819f3740_a96493be","filename":"56f120473cece6a6e2167b36819f3740_a96493be.jpg","filesize":491638,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/56f120473cece6a6e2167b36819f3740_a96493be-2\/","alt":"","author":"0","description":"","caption":"","name":"56f120473cece6a6e2167b36819f3740_a96493be-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:44","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","2048x2048-width":1620,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169532,"id":169532,"title":"1d661b27034707f6e632fba680589e14_fb21ec4e","filename":"1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","filesize":487474,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/1d661b27034707f6e632fba680589e14_fb21ec4e-2\/","alt":"","author":"0","description":"","caption":"","name":"1d661b27034707f6e632fba680589e14_fb21ec4e-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:46","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1619,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","2048x2048-width":1619,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169539,"id":169539,"title":"dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76","filename":"dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","filesize":150588,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-2\/","alt":"","author":"0","description":"","caption":"","name":"dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:47","modified":"2025-04-18 13:00:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169546,"id":169546,"title":"f898aed797c695793de66299c05b9086_eeeb1d67","filename":"f898aed797c695793de66299c05b9086_eeeb1d67.jpg","filesize":98566,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/life-hotel\/f898aed797c695793de66299c05b9086_eeeb1d67-2\/","alt":"","author":"0","description":"","caption":"","name":"f898aed797c695793de66299c05b9086_eeeb1d67-2","status":"inherit","uploaded_to":178422,"date":"2025-04-18 09:08:47","modified":"2025-04-18 13:00:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Situ\u00e9 aux portes de Bergame, le Life Hotel accueille ses h\u00f4tes dans une structure accueillante, \u00e9l\u00e9gante et respectueuse de l&#8217;environnement, avec une certification Leed Gold. Un lieu o\u00f9 la nature devient source d&#8217;inspiration, dans lequel on peut profiter d&#8217;un long ou d&#8217;un court s\u00e9jour au nom du bien-\u00eatre. Partie int\u00e9grante du p\u00f4le Life Source, le confort des chambres et des suites de l&#8217;h\u00f4tel ****S s&#8217;int\u00e8gre aux diff\u00e9rentes exp\u00e9riences du groupe : de la Food Experience dans ses trois formats gastronomiques diff\u00e9rents \u00e0 l&#8217;espace Wellness avec SPA et espace fitness, ici chaque moment est une occasion de plaisir.&#13;<br \/>\n\u00a0&#13;<br \/>\nChaque chambre et suite du Life Hotel est dot\u00e9e de :&#13;<br \/>\n&#8211; Lits Dorelan de haute qualit\u00e9, pour un sommeil agr\u00e9able et confortable pendant votre s\u00e9jour ;&#13;<br \/>\n&#8211; T\u00e9l\u00e9vision avec syst\u00e8me Chromecast qui vous permet de profiter du contenu en streaming (sur demande, payant) ;&#13;<br \/>\n&#8211; Insonorisation des chambres.&#13;<br \/>\n\u00a0&#13;<br \/>\nLes chambres du Life Hotel sont dot\u00e9es d&#8217;\u00e9quipements \u00e0 la pointe de la technologie : de la r\u00e9gulation de la temp\u00e9rature interne \u00e0 la gestion avanc\u00e9e de l&#8217;\u00e9clairage et tant d&#8217;autres choses, facilement accessibles et r\u00e9glables par les clients en fonction de leurs besoins.&#13;<br \/>\nL&#8217;endroit se pr\u00eate aux r\u00e9unions et aux rencontres d&#8217;affaires, gr\u00e2ce \u00e9galement \u00e0 ses salles de r\u00e9union, dot\u00e9es encore une fois d&#8217;un \u00e9quipement technologique de pointe et de grandes fen\u00eatres qui laissent passer la lumi\u00e8re naturelle.&#13;<br \/>\nLe palais est le protagoniste d&#8217;un s\u00e9jour au Life Hotel. En effet, les h\u00f4tes pourront profiter des trois propositions gastronomiques du centre : le restaurant Le Terre, pour une cuisine gastronomique de haut niveau et surprenante, Onda Bistrot, pour une cuisine &#8216;pop&#8217; simple et d\u00e9licieuse, et Atmosfere Rooftop &#8211; la terrasse avec vue panoramique sur les collines de Bergame &#8211; pour des moments de l\u00e9g\u00e8ret\u00e9 en plein air.&#13;<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.689193","longitude":"9.646426","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"LIFE SOURCE s.r.l.","registered_office":"","iu_addr_streetnumber":"Via Briantea, 5","iu_addr_postalcode":"24128","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035 05 26 169","iu_cell":"","iu_website":"http:\/\/www.lifehotelbergamo.it","iu_email":"info@lifehotelbergamo.it","iu_vat":"03678420161","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"4","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"10174","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"parking","label":"Parcheggio gratuito"},{"value":"elevator","label":"Ascensore"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"pool","label":"Piscina"},{"value":"restaurant","label":"Ristorante"},{"value":"health_club","label":"Centro benessere"},{"value":"bar","label":"Bar"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"sauna","label":"Sauna"},{"value":"shower","label":"Bagni con doccia"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"room_service","label":"Servizio in camera"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"mini_bar","label":"Frigo bar"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/178422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/178422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/169448"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=178422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=178422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=178422"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=178422"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=178422"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=178422"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=178422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}