{"id":178500,"date":"2025-04-18T13:34:19","date_gmt":"2025-04-18T11:34:19","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/spiazzi\/"},"modified":"2025-04-18T15:04:14","modified_gmt":"2025-04-18T13:04:14","slug":"spiazzi","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/","title":{"rendered":"Spiazzi"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":172046,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-178500","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Spiazzi","hero_text":"<p>Le lieu id\u00e9al pour se d\u00e9tendre, immerg\u00e9 dans la nature d&#8217;un village de montagne<\/p>\n","slides":[{"image":{"ID":172046,"id":172046,"title":"746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","filename":"746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","filesize":340954,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/746ce906995207498a5c0d82e744c06c_a003a2c7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"746ce906995207498a5c0d82e744c06c_a003a2c7-jpg-2","status":"inherit","uploaded_to":178500,"date":"2025-04-18 09:18:34","modified":"2025-04-18 13:04:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":494,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7-300x94.jpg","medium-width":300,"medium-height":94,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7-768x240.jpg","medium_large-width":768,"medium_large-height":240,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7-1024x320.jpg","large-width":1024,"large-height":320,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7-1536x480.jpg","1536x1536-width":1536,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","2048x2048-width":1580,"2048x2048-height":494,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":94,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":125,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/746ce906995207498a5c0d82e744c06c_a003a2c7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":188}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":172053,"id":172053,"title":"5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","filename":"5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","filesize":285595,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/5c743a1f25651abafe58ee14f99c7290_66b587b6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5c743a1f25651abafe58ee14f99c7290_66b587b6-jpg-2","status":"inherit","uploaded_to":178500,"date":"2025-04-18 09:18:35","modified":"2025-04-18 13:04:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":636,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6-300x121.jpg","medium-width":300,"medium-height":121,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6-768x309.jpg","medium_large-width":768,"medium_large-height":309,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6-1024x412.jpg","large-width":1024,"large-height":412,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6-1536x618.jpg","1536x1536-width":1536,"1536x1536-height":618,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","2048x2048-width":1580,"2048x2048-height":636,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":121,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":161,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5c743a1f25651abafe58ee14f99c7290_66b587b6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":242}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":172060,"id":172060,"title":"a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","filename":"a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","filesize":519403,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/a3cc4f648e656012421c813362928f17_4e0fe6c9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a3cc4f648e656012421c813362928f17_4e0fe6c9-jpg-2","status":"inherit","uploaded_to":178500,"date":"2025-04-18 09:18:36","modified":"2025-04-18 13:04:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":693,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9-300x132.jpg","medium-width":300,"medium-height":132,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9-768x337.jpg","medium_large-width":768,"medium_large-height":337,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9-1024x449.jpg","large-width":1024,"large-height":449,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9-1536x674.jpg","1536x1536-width":1536,"1536x1536-height":674,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","2048x2048-width":1580,"2048x2048-height":693,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":132,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3cc4f648e656012421c813362928f17_4e0fe6c9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":263}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":172067,"id":172067,"title":"98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","filename":"98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","filesize":388362,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-jpg-2","status":"inherit","uploaded_to":178500,"date":"2025-04-18 09:18:38","modified":"2025-04-18 13:04:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":626,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-300x119.jpg","medium-width":300,"medium-height":119,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-768x304.jpg","medium_large-width":768,"medium_large-height":304,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-1024x406.jpg","large-width":1024,"large-height":406,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00-1536x609.jpg","1536x1536-width":1536,"1536x1536-height":609,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","2048x2048-width":1580,"2048x2048-height":626,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":119,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":158,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98fc728fd57a2a5d9674c015af2ca8dd_8229ab00.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":238}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":172074,"id":172074,"title":"3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","filename":"3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","filesize":333714,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-jpg-2","status":"inherit","uploaded_to":178500,"date":"2025-04-18 09:18:39","modified":"2025-04-18 13:04:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":708,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-300x134.jpg","medium-width":300,"medium-height":134,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-768x344.jpg","medium_large-width":768,"medium_large-height":344,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-1024x459.jpg","large-width":1024,"large-height":459,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5-1536x688.jpg","1536x1536-width":1536,"1536x1536-height":688,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","2048x2048-width":1580,"2048x2048-height":708,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":134,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":179,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3a4bc29a7e8576a606a387a5b07336ad_1fbe9ff5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":269}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":172081,"id":172081,"title":"fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","filename":"fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","filesize":535565,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/spiazzi\/fa8afedece086cdf058c20dca4a0013c_8128f75d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fa8afedece086cdf058c20dca4a0013c_8128f75d-jpg-2","status":"inherit","uploaded_to":178500,"date":"2025-04-18 09:18:40","modified":"2025-04-18 13:04:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":606,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d-300x115.jpg","medium-width":300,"medium-height":115,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d-768x295.jpg","medium_large-width":768,"medium_large-height":295,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d-1024x393.jpg","large-width":1024,"large-height":393,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d-1536x589.jpg","1536x1536-width":1536,"1536x1536-height":589,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","2048x2048-width":1580,"2048x2048-height":606,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":115,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":153,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa8afedece086cdf058c20dca4a0013c_8128f75d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":230}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>L&#8217;h\u00f4tel Spiazzi est situ\u00e9 \u00e0 Spiazzi di Gromo, dans la Valle Seriana, \u00e0 quelques pas des remont\u00e9es m\u00e9caniques et dans un paysage naturel pr\u00e9serv\u00e9.&#13;<br \/>\nLa famille Olivari vous attend dans un lieu chaleureux et accueillant, o\u00f9 vous pourrez s\u00e9journer et profiter de la salle de restaurant pour vos repas et du bar avec v\u00e9randa pour une pause rafra\u00eechissement.&#13;<br \/>\nLes services de l&#8217;h\u00f4tel sont :&#13;<br \/>\n&#13;<br \/>\n60 chambres avec salle de bains, t\u00e9l\u00e9phone et t\u00e9l\u00e9vision\u00a0; chambres doubles, chambres doubles \u00e0 usage individuel et chambres multiples adapt\u00e9es aux familles et aux groupes&#13;<br \/>\nAscenseur&#13;<br \/>\nRestaurant 300 places&#13;<br \/>\nBar avec v\u00e9randa&#13;<br \/>\nSalle cin\u00e9ma&#13;<br \/>\nPing-pong et baby-foot&#13;<br \/>\nCoin d\u00e9tente avec musique&#13;<br \/>\nSki room&#13;<br \/>\nTerrasse panoramique&#13;<br \/>\nEspace polyvalent couvert en plein air&#13;<br \/>\nPatinage sur glace en hiver dans une structure priv\u00e9e&#13;<br \/>\nD\u00e9p\u00f4t de v\u00e9los dans une zone vid\u00e9o surveill\u00e9e&#13;<br \/>\n&#13;<br \/>\nPr\u00e8s de l&#8217;h\u00f4tel :&#13;<br \/>\n&#13;<br \/>\nRemont\u00e9es m\u00e9caniques, \u00e9cole de ski&#13;<br \/>\nLocation de skis, raquettes, bobsleigh, snowboard&#13;<br \/>\nLocation de v\u00e9los pour downhill&#13;<br \/>\nTir \u00e0 l&#8217;arc&#13;<br \/>\nParc accrobranche suspendu dans les bois&#13;<br \/>\nPiste de bobsleigh d&#8217;\u00e9t\u00e9&#13;<br \/>\nTrampolines&#13;<br \/>\nExcursions tout niveau&#13;<br \/>\n&#13;<br \/>\nProfitez de vacances \u00e0 l&#8217;h\u00f4tel Spiazzi proposant moments de d\u00e9tente, aventure et sport : autant d&#8217;exp\u00e9riences \u00e0 vivre dans un paysage bergamasque pr\u00e9serv\u00e9, \u00e0 quelques pas de l&#8217;h\u00f4tel.\u00a0<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.970289","longitude":"9.963279","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24020","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39034647000","iu_cell":"","iu_website":"https:\/\/www.hotelspiazzi.it\/","iu_email":"contatto@hotelspiazzi.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"3","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"4562","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"restaurant","label":"Ristorante"},{"value":"wifi","label":"Wi-Fi"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/178500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/178500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/172046"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=178500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=178500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=178500"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=178500"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=178500"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=178500"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=178500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}