{"id":36160,"date":"2025-06-08T14:57:31","date_gmt":"2025-06-08T12:57:31","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/promenade-avec-guide-audio-et-aperitif-a-bergame-haute\/"},"modified":"2025-05-12T20:05:09","modified_gmt":"2025-05-12T18:05:09","slug":"promenade-avec-guide-audio-et-aperitif-a-bergame-haute","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/promenade-avec-guide-audio-et-aperitif-a-bergame-haute\/","title":{"rendered":"Promenade avec guide audio et ap\u00e9ritif \u00e0 Bergame Haute"},"excerpt":{"rendered":"<p>Acheter l&#8217;exp\u00e9rience par le biais d&#8217;un bon d&#8217;achat utilisable sur une p\u00e9riode de 6 mois<\/p>\n","protected":false},"author":0,"featured_media":184240,"template":"","categories":[521,523],"tags":[],"aggr":[],"area":[],"kind":[18704],"zona":[],"class_list":["post-36160","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experience","kind-esperienza-fr"],"acf":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Promenade avec guide audio et ap\u00e9ritif \u00e0 Bergame Haute","hero_text":"<p>Acheter l&#8217;exp\u00e9rience par le biais d&#8217;un bon d&#8217;achat utilisable sur une p\u00e9riode de 6 mois<\/p>\n","slides":[{"image":{"ID":184240,"id":184240,"title":"ec_service_3764_1","filename":"ec_service_3764_1.jpg","filesize":86594,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/promenade-avec-guide-audio-et-aperitif-a-bergame-haute\/ec_service_3764_1-2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_3764_1-2-2","status":"inherit","uploaded_to":36160,"date":"2025-04-22 17:49:30","modified":"2025-05-12 18:05:10","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":488,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1-300x122.jpg","medium-width":300,"medium-height":122,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1-768x312.jpg","medium_large-width":768,"medium_large-height":312,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1-1024x416.jpg","large-width":1024,"large-height":416,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1.jpg","1536x1536-width":1200,"1536x1536-height":488,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1.jpg","2048x2048-width":1200,"2048x2048-height":488,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":122,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":163,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_3764_1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":244}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>-D\u00e9couvrir la beaut\u00e9 de Bergame Haute<br \/>\n-Ap\u00e9ritif avec des produits locaux<\/p>\n<p>CE QUI VOUS ATTEND<br \/>\nVous recevrez un code pour t\u00e9l\u00e9charger sur votre smartphone un guide audio qui vous emm\u00e8nera \u00e0 la d\u00e9couverte des beaut\u00e9s de la ville de Bergame.<br \/>\nVous pourrez ensuite vous promener dans les rues du centre-ville tout en \u00e9coutant confortablement depuis votre t\u00e9l\u00e9phone des r\u00e9cits sur l&#8217;histoire, l&#8217;art et la tradition des principaux points d&#8217;int\u00e9r\u00eat de la ville.<br \/>\n\u00c0 la fin de la visite, un ap\u00e9ritif de sp\u00e9cialit\u00e9s locales vous attend, avec un verre de vin ou une boisson.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Toute l&#8217;ann\u00e9e<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Pas de remboursement en cas de non-pr\u00e9sentation<br \/>\nAnnulation gratuite jusqu&#8217;\u00e0 7 jours avant la date de l&#8217;exp\u00e9rience.<br \/>\nSi l&#8217;annulation n&#8217;est pas effectu\u00e9e dans les 7 jours pr\u00e9c\u00e9dant le service, le montant total vous sera demand\u00e9.<\/p>\n","moredetails":"<p>R\u00e9servations :<br \/>\nEn effectuant une r\u00e9servation, vous achetez un bon d&#8217;achat qui peut \u00eatre utilis\u00e9 dans les 6 prochains mois, que vous pouvez aussi offrir. Vous pourrez alors contacter Incoming Bergamo &#038; Italy de Brembo Viaggi pour convenir de la date choisie et du point de rencontre exact dans Bergame Haute.<br \/>\nVous trouverez les coordonn\u00e9es de Incoming Bergamo &#038; Italy dans la confirmation de commande que vous recevrez imm\u00e9diatement apr\u00e8s votre achat.<\/p>\n","whatsincluded":"<p>-guide audio de Bergame et Brescia utilisable sur votre smartphone ;<br \/>\n-ap\u00e9ritif avec un verre de vin\/boisson accompagn\u00e9 de produits typiques ;<br \/>\n-assurance bagages et m\u00e9dicale de base<\/p>\n","whatsnotincluded":"<p>Tout ce qui n&#8217;est pas indiqu\u00e9 dans &#8220;CE QUI EST INCLUS&#8221; .<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.70407330","longitude":"9.66271280","startingprice":"49.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Piazza Vecchia","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Incoming Bergamo & Italy - Brembo Viaggi, Via Pontesecco, 7, Ponteranica","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=3764&serviceid=1","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"2h","iu_languages":"fran\u00e7ais - anglais - italien - espagnol - allemand","iu_minpeople":"Minimum 1 personne","iu_maxpeople":"Maximum 10 personnes","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_3764_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"30\/03\/2023","validto":"31\/12\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/36160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/36160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/184240"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=36160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=36160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=36160"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=36160"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=36160"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=36160"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=36160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}