{"id":70082,"date":"2025-06-08T14:58:55","date_gmt":"2025-06-08T12:58:55","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/e-bike-tour-en-valzurio-les-chalets-de-moschel-et-les-marmites-des-geants\/"},"modified":"2025-05-12T20:07:28","modified_gmt":"2025-05-12T18:07:28","slug":"e-bike-tour-en-valzurio-les-chalets-de-moschel-et-les-marmites-des-geants","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/e-bike-tour-en-valzurio-les-chalets-de-moschel-et-les-marmites-des-geants\/","title":{"rendered":"E-bike Tour en Valzurio : Les chalets de Moschel et les Marmites des G\u00e9ants"},"excerpt":{"rendered":"<p>Guide VTT et location de e-bike incluses.<br \/>\nAchetez votre bon valable pendant 12 mois.<\/p>\n","protected":false},"author":0,"featured_media":184485,"template":"","categories":[521,523],"tags":[17261],"aggr":[],"area":[],"kind":[18704],"zona":[],"class_list":["post-70082","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experience","tag-tourisme-a-velo-fr","kind-esperienza-fr"],"acf":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"E-bike Tour en Valzurio : Les chalets de Moschel et les Marmites des G\u00e9ants","hero_text":"<p>Guide VTT et location de e-bike incluses.<br \/>\nAchetez votre bon valable pendant 12 mois.<\/p>\n","slides":[{"image":{"ID":184485,"id":184485,"title":"ec_service_4281_1","filename":"ec_service_4281_1.jpg","filesize":150245,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/e-bike-tour-en-valzurio-les-chalets-de-moschel-et-les-marmites-des-geants\/ec_service_4281_1-2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4281_1-2-2","status":"inherit","uploaded_to":70082,"date":"2025-04-22 17:50:41","modified":"2025-05-12 18:07:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":551,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1-768x353.jpg","medium_large-width":768,"medium_large-height":353,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1-1024x470.jpg","large-width":1024,"large-height":470,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1.jpg","1536x1536-width":1200,"1536x1536-height":551,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1.jpg","2048x2048-width":1200,"2048x2048-height":551,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":138,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":184,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4281_1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":276}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":69993,"id":69993,"title":"ec_service_4281_1_2.jpg","filename":"ec_service_4281_1_2.jpg","filesize":135629,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/e-bike-tour-en-valzurio-les-chalets-de-moschel-et-les-marmites-des-geants\/ec_service_4281_1_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4281_1_2-jpg-2","status":"inherit","uploaded_to":70082,"date":"2024-07-08 16:35:36","modified":"2025-05-12 18:07:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":572,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2-300x143.jpg","medium-width":300,"medium-height":143,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2-768x366.jpg","medium_large-width":768,"medium_large-height":366,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2-1024x488.jpg","large-width":1024,"large-height":488,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2.jpg","1536x1536-width":1200,"1536x1536-height":572,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2.jpg","2048x2048-width":1200,"2048x2048-height":572,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":143,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":191,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":286}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":69999,"id":69999,"title":"ec_service_4281_1_3.jpg","filename":"ec_service_4281_1_3.jpg","filesize":86630,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/e-bike-tour-en-valzurio-les-chalets-de-moschel-et-les-marmites-des-geants\/ec_service_4281_1_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4281_1_3-jpg-2","status":"inherit","uploaded_to":70082,"date":"2024-07-08 16:35:39","modified":"2025-05-12 18:07:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":429,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3.jpg","1536x1536-width":1200,"1536x1536-height":429,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3.jpg","2048x2048-width":1200,"2048x2048-height":429,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/ec_service_4281_1_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>&#8211; Une excursion en e-bike de 4 heures avec un guide certifi\u00e9<br \/>\n&#8211; Vous serez entour\u00e9 par un paysage montagneux et profiterez de panoramas \u00e0 couper le souffle<\/p>\n<p>CE QUI VOUS ATTEND<br \/>\nVous rencontrerez Enzo, votre guide VTT, au point de location de e-bikes. Vous recevrez un bref briefing sur la tourn\u00e9e et l&#8217;utilisation du e-bike avant de commencer l&#8217;excursion \u00e0 v\u00e9lo.<br \/>\nLe parcours est immerg\u00e9 dans les bois de Valzurio, avec des sentiers qui s&#8217;ouvrent sur des vues magnifiques.<br \/>\nLe parcours m\u00e8ne aux Chalets de Moschel, d&#8217;o\u00f9 vous admirerez la Presolana, appel\u00e9e par les Bergamasques &#8220;la reine des Orobie&#8221;, la seule montagne dolomitique de notre arc pr\u00e9alpin.<br \/>\nEnfin, pour ceux qui le souhaitent, le tour continue vers les &#8220;Marmites des G\u00e9ants&#8221; : des piscines naturelles d&#8217;eau cristalline.<br \/>\n\u00c0 votre retour de l&#8217;excursion, il est possible de s&#8217;arr\u00eater pour un caf\u00e9 ou un ap\u00e9ritif \u00e0 la Baita Valle Azzurra.<\/p>\n<p>Le parcours est de difficult\u00e9 moyenne, \u00e0 la fois sur l&#8217;asphalte et sur les sentiers de montagne, n\u00e9cessitant une familiarit\u00e9 minimale avec le v\u00e9lo et l&#8217;habitude de rester en selle pendant plusieurs heures.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Toute l&#8217;ann\u00e9e<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Aucun remboursement en cas de non-pr\u00e9sentation.<br \/>\nAnnulation gratuite jusqu&#8217;\u00e0 5 jours avant l&#8217;exp\u00e9rience.<\/p>\n","moredetails":"<p>Le parcours est de 28 km au total. Le d\u00e9nivel\u00e9 est de 850 m\u00e8tres.<\/p>\n<p>R\u00e9servations :<br \/>\nEn effectuant la r\u00e9servation, vous achetez un bon valable pendant 12 mois, qui peut \u00e9galement \u00eatre offert. Vous pourrez ensuite contacter E-bike Tour sul Serio pour choisir la date et obtenir les d\u00e9tails de la location du v\u00e9lo (taille et type de e-bike). Les coordonn\u00e9es de E-bike Tour sul Serio seront incluses dans la confirmation de commande que vous recevrez imm\u00e9diatement apr\u00e8s l&#8217;achat.<\/p>\n<p>Vous souhaitez r\u00e9server l&#8217;exp\u00e9rience pour une date sp\u00e9cifique et \u00eatre s\u00fbr de la disponibilit\u00e9 du guide ? Cliquez sur &#8220;contactez-nous&#8221; et \u00e9crivez-nous tout ce que vous souhaitez savoir. Nous r\u00e9pondons dans les 24 heures !<\/p>\n<p>Il est recommand\u00e9 de porter des v\u00eatements confortables et sportifs avec des chaussures ferm\u00e9es (baskets ou chaussures de randonn\u00e9e) et d&#8217;apporter un petit sac \u00e0 dos avec une gourde d&#8217;eau.<\/p>\n","whatsincluded":"<p>&#8211; Accompagnement avec guide VTT certifi\u00e9<br \/>\n&#8211; Location de e-bike<br \/>\n&#8211; Casque<br \/>\n&#8211; Assurance responsabilit\u00e9 civile<\/p>\n","whatsnotincluded":"<p>&#8211; Transport pour se rendre sur le lieu de l&#8217;exp\u00e9rience<br \/>\n&#8211; Repas, caf\u00e9, ap\u00e9ritifs<br \/>\n&#8211; Pourboires et \u00e9ventuels extras<br \/>\n&#8211; Tout ce qui n&#8217;est pas indiqu\u00e9 dans &#8220;ce qui est inclus&#8221;<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"","longitude":"","startingprice":"75.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"E-bike Tour sul Serio, Via A. Locatelli, 18, Ardesio","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=4281&serviceid=1","iu_videourl":"","iu_difficulty":"Moyenne","iu_accessibility":"","iu_duration":"4h","iu_languages":"italien","iu_minpeople":"Minimum 2 personnes","iu_maxpeople":"Maximum 8 personnes","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4281_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"14\/06\/2024","validto":"14\/06\/2034","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>&#8211; Une excursion en e-bike de 4 heures avec un guide certifi\u00e9<br \/>\n&#8211; Vous serez entour\u00e9 par un paysage montagneux et profiterez de panoramas \u00e0 couper le souffle<\/p>\n<p>CE QUI VOUS ATTEND<br \/>\nVous rencontrerez Enzo, votre guide VTT, au point de location de e-bikes. Vous recevrez un bref briefing sur la tourn\u00e9e et l&#8217;utilisation du e-bike avant de commencer l&#8217;excursion \u00e0 v\u00e9lo.<br \/>\nLe parcours est immerg\u00e9 dans les bois de Valzurio, avec des sentiers qui s&#8217;ouvrent sur des vues magnifiques.<br \/>\nLe parcours m\u00e8ne aux Chalets de Moschel, d&#8217;o\u00f9 vous admirerez la Presolana, appel\u00e9e par les Bergamasques &#8220;la reine des Orobie&#8221;, la seule montagne dolomitique de notre arc pr\u00e9alpin.<br \/>\nEnfin, pour ceux qui le souhaitent, le tour continue vers les &#8220;Marmites des G\u00e9ants&#8221; : des piscines naturelles d&#8217;eau cristalline.<br \/>\n\u00c0 votre retour de l&#8217;excursion, il est possible de s&#8217;arr\u00eater pour un caf\u00e9 ou un ap\u00e9ritif \u00e0 la Baita Valle Azzurra.<\/p>\n<p>Le parcours est de difficult\u00e9 moyenne, \u00e0 la fois sur l&#8217;asphalte et sur les sentiers de montagne, n\u00e9cessitant une familiarit\u00e9 minimale avec le v\u00e9lo et l&#8217;habitude de rester en selle pendant plusieurs heures.<\/p>\n","indepth":"","latitude":"","longitude":"","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","timerange":"<p>Toute l&#8217;ann\u00e9e<\/p>\n","cancellationpolicy":"<p>Aucun remboursement en cas de non-pr\u00e9sentation.<br \/>\nAnnulation gratuite jusqu&#8217;\u00e0 5 jours avant l&#8217;exp\u00e9rience.<\/p>\n","moredetails":"<p>Le parcours est de 28 km au total. Le d\u00e9nivel\u00e9 est de 850 m\u00e8tres.<\/p>\n<p>R\u00e9servations :<br \/>\nEn effectuant la r\u00e9servation, vous achetez un bon valable pendant 12 mois, qui peut \u00e9galement \u00eatre offert. Vous pourrez ensuite contacter E-bike Tour sul Serio pour choisir la date et obtenir les d\u00e9tails de la location du v\u00e9lo (taille et type de e-bike). Les coordonn\u00e9es de E-bike Tour sul Serio seront incluses dans la confirmation de commande que vous recevrez imm\u00e9diatement apr\u00e8s l&#8217;achat.<\/p>\n<p>Vous souhaitez r\u00e9server l&#8217;exp\u00e9rience pour une date sp\u00e9cifique et \u00eatre s\u00fbr de la disponibilit\u00e9 du guide ? Cliquez sur &#8220;contactez-nous&#8221; et \u00e9crivez-nous tout ce que vous souhaitez savoir. Nous r\u00e9pondons dans les 24 heures !<\/p>\n<p>Il est recommand\u00e9 de porter des v\u00eatements confortables et sportifs avec des chaussures ferm\u00e9es (baskets ou chaussures de randonn\u00e9e) et d&#8217;apporter un petit sac \u00e0 dos avec une gourde d&#8217;eau.<\/p>\n","whatsincluded":"<p>&#8211; Accompagnement avec guide VTT certifi\u00e9<br \/>\n&#8211; Location de e-bike<br \/>\n&#8211; Casque<br \/>\n&#8211; Assurance responsabilit\u00e9 civile<\/p>\n","whatsnotincluded":"<p>&#8211; Transport pour se rendre sur le lieu de l&#8217;exp\u00e9rience<br \/>\n&#8211; Repas, caf\u00e9, ap\u00e9ritifs<br \/>\n&#8211; Pourboires et \u00e9ventuels extras<br \/>\n&#8211; Tout ce qui n&#8217;est pas indiqu\u00e9 dans &#8220;ce qui est inclus&#8221;<\/p>\n","startingprice":"75.00","id_madeep":"652_4281_1","iu_minpeople":"Minimum 2 personnes","iu_maxpeople":"Maximum 8 personnes","iu_languages":"italien","iu_duration":"4h","iu_difficulty":"Moyenne","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=4281&serviceid=1","iu_manager":"E-bike Tour sul Serio, Via A. Locatelli, 18, Ardesio","review":false,"validfrom":"14\/06\/2024","validto":"14\/06\/2034"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/70082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/70082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/184485"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=70082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=70082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=70082"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=70082"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=70082"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=70082"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=70082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}