{"id":81062,"date":"2025-05-12T10:56:11","date_gmt":"2025-05-12T08:56:11","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/albergo-ristorante-della-torre\/"},"modified":"2025-05-12T10:24:59","modified_gmt":"2025-05-12T08:24:59","slug":"albergo-ristorante-della-torre-2","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/albergo-ristorante-della-torre-2\/","title":{"rendered":"Albergo Ristorante Della Torre"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":80999,"template":"","categories":[855],"tags":[],"aggr":[],"area":[],"kind":[18719],"zona":[],"class_list":["post-81062","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-855","kind-ristorante-fr"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Albergo Ristorante Della Torre","hero_text":"","slides":[{"image":{"ID":80999,"id":80999,"title":"della-torre.jpg","filename":"della-torre.jpg","filesize":748494,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/albergo-ristorante-della-torre-2\/della-torre-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"della-torre-jpg-2","status":"inherit","uploaded_to":81062,"date":"2024-10-02 09:22:51","modified":"2025-05-12 08:24:59","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":898,"height":393,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre-768x336.jpg","medium_large-width":768,"medium_large-height":336,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","large-width":898,"large-height":393,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","1536x1536-width":898,"1536x1536-height":393,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","2048x2048-width":898,"2048x2048-height":393,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/10\/della-torre.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":263}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Albergo Ristorante Della Torre","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>LE RESTAURANT&#13;<br \/>\nLa passion et l&#8217;amour pour le territoire et les mati\u00e8res premi\u00e8res qu&#8217;il offre sont les deux piliers de la longue tradition culinaire du Ristorante della Torre, dirig\u00e9 par le Chef Diego Pavesi.&#13;<br \/>\nEn activit\u00e9 depuis 1898, avec les premi\u00e8res traces document\u00e9es de la gestion familiale Pavesi\/Rudelli, le restaurant est situ\u00e9 dans le m\u00eame h\u00f4tel, nich\u00e9 au pied de la tour du XIVe si\u00e8cle.&#13;<br \/>\nLa Sala del Pozzo, habilement r\u00e9nov\u00e9e (avec une v\u00e9randa d&#8217;\u00e9t\u00e9), propose une cuisine cr\u00e9ative aux profondes racines traditionnelles, bas\u00e9e sur des mati\u00e8res premi\u00e8res de qualit\u00e9, la cr\u00e9ativit\u00e9 et le savoir-faire du Chef et Patron Diego Pavesi.&#13;<br \/>\nLa Sala Rosa offre un cadre plus classique, proposant des plats traditionnels de la cuisine lombarde et italienne, en utilisant exclusivement des ingr\u00e9dients s\u00e9lectionn\u00e9s, de pr\u00e9f\u00e9rence locaux (km 0) ou nationaux.&#13;<br \/>\nUn autre atout est la cave \u00e0 vin, l&#8217;une des mieux fournies de la r\u00e9gion de Bergame, offrant un large choix de vins nationaux et internationaux, conserv\u00e9s dans un cadre enchanteur.&#13;<br \/>\nActuellement, un passage g\u00e9n\u00e9rationnel est en cours de pr\u00e9paration, permettant \u00e0 la cinqui\u00e8me g\u00e9n\u00e9ration de poursuivre et moderniser toute la structure.&#13;<br \/>\n&#13;<br \/>\nLE CHEF&#13;<br \/>\nDiego Pavesi&#13;<br \/>\nEn cuisine, Diego Pavesi propose des sp\u00e9cialit\u00e9s gastronomiques qui s&#8217;inspirent \u00e0 la fois de la culture culinaire traditionnelle de Bergame et d&#8217;influences du monde entier, en associant des plats typiques lombards \u00e0 des cr\u00e9ations innovantes.&#13;<br \/>\nLe chef puise dans les inspirations et exp\u00e9riences acquises dans des restaurants \u00e9toil\u00e9s en Italie et en France, notamment au Ristorante &#8220;Antica Osteria del Ponte&#8221; \u00e0 Cassinetta di Lugagnano avec le Chef ex\u00e9cutif &#038; Patron Ezio Santin, ainsi qu&#8217;au Ristorante &#8220;Louis XV&#8221; \u00e0 Monaco avec le Chef ex\u00e9cutif Alain Ducasse.&#13;<br \/>\nAu cours de sa carri\u00e8re, Diego a re\u00e7u d&#8217;importantes distinctions et reconnaissances, notamment : Sole di Veronelli, M\u00e9daille d&#8217;or d\u00e9cern\u00e9e par la F\u00e9d\u00e9ration italienne des chefs et ASS Provincial Chefs de C\u00f4me en 2003.&#13;<br \/>\nLe Prix M\u00e9daille d&#8217;Or pour l&#8217;ensemble de sa carri\u00e8re en 2011, pour avoir valoris\u00e9 la cat\u00e9gorie avec comp\u00e9tence et prestige, tout en honorant toujours la tradition de l&#8217;art culinaire, remis par l&#8217;Association des chefs de C\u00f4me et la F\u00e9d\u00e9ration italienne des chefs.&#13;<br \/>\n3\u00e8me place dans la cat\u00e9gorie &#8220;International Attitude&#8221; lors du Concours InAlto by Bormioli Rocco en 2016.&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.695388485114","longitude":"9.8408844561569","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Piazza Cavour","iu_addr_postalcode":"24069","iu_addr_city":"Trescore Balneario","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@albergotorre.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"352","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/81062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/81062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/80999"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=81062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=81062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=81062"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=81062"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=81062"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=81062"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=81062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}