{"id":84920,"date":"2024-06-05T16:27:14","date_gmt":"2024-06-05T14:27:14","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/itineraire-vers-le-belvedere-des-collines-de-san-fermo\/"},"modified":"2024-10-08T17:05:14","modified_gmt":"2024-10-08T15:05:14","slug":"itineraire-vers-le-belvedere-des-collines-de-san-fermo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/itineraire-vers-le-belvedere-des-collines-de-san-fermo\/","title":{"rendered":"Itin\u00e9raire vers le Belv\u00e9d\u00e8re des collines de San Fermo"},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18684],"zona":[],"class_list":["post-84920","oggetto","type-oggetto","status-publish","hentry","kind-itinerario-fr"],"acf":{"featured_video":false,"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Statistiques sur les itin\u00e9raires"},"tcm_ui":[{"label":"Dur\u00e9e moyenne du voyage","value":"30'"},{"label":"Longueur","value":"1,04 km"},{"label":"Diff\u00e9rence de hauteur positive","value":"30 m"},{"label":"Difficult\u00e9s techniques","value":"moyen"},{"label":"Diff\u00e9rence de hauteur n\u00e9gative","value":"30 m"},{"label":"Altitude maximale","value":"1246 m"},{"label":"Altitude minimale","value":"1211 m"},{"label":"Type d'itin\u00e9raire","value":"anneau"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p><span style=\"font-weight: 400;\">D\u00e9couvrez les tr\u00e9sors naturels et historiques du Val Cavallina et l&#8217;itin\u00e9raire accessible des Colli San Fermo.<br \/>\nUn itin\u00e9raire \u00e0 couper le souffle rendu possible par le projet S.T.A.I. et l&#8217;initiative &#8220;CamminaOrobie&#8221;. <\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Val Cavallina et Colli San Fermo : une exp\u00e9rience incroyable<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Au nord-est de Bergame, l&#8217;enchanteresse <strong>Val Cavallina<\/strong> vous surprendra par ses tr\u00e9sors naturels et historiques, du <strong>lac Endine<\/strong> aux anciens ch\u00e2teaux, des <strong>Pr\u00e9alpes d&#8217;Orobie<\/strong> qui l&#8217;entourent aux fascinants sentiers qui la traversent.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;une des plus belles \u00e9tapes est sans aucun doute <\/span><b>Les collines de San Fermo<\/b><span style=\"font-weight: 400;\">L&#8217;h\u00f4tel est situ\u00e9 sur le <strong>Monte Ballerino<\/strong>, \u00e0 deux pas du ciel et des grands lacs de la r\u00e9gion de Bergame.<br \/>\nSes hauteurs offrent une vue imprenable non seulement sur la plaine et le lac Endine, mais aussi sur l&#8217;Orobie et, plus loin, sur les <strong>Alpes rh\u00e9tiques<\/strong> enneig\u00e9es. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-37767\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Berzo_San_Fermo_Paesaggio_TB077-Paolo-Ardiani-1024x396.jpg\" alt=\"\" width=\"1024\" height=\"396\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Berzo_San_Fermo_Paesaggio_TB077-Paolo-Ardiani-1024x396.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Berzo_San_Fermo_Paesaggio_TB077-Paolo-Ardiani-300x116.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Berzo_San_Fermo_Paesaggio_TB077-Paolo-Ardiani-768x297.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Berzo_San_Fermo_Paesaggio_TB077-Paolo-Ardiani-1536x595.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Berzo_San_Fermo_Paesaggio_TB077-Paolo-Ardiani-2048x793.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"D\u00e9tails techniques"},"tcm_ui":[{"label":"Classement","value":"AT (accessible aux touristes)"},{"label":"Convient aux appareils","value":"entra\u00eenement \u00e9lectronique pour fauteuils roulants, Jolette, fauteuils roulants avec accompagnateur"},{"label":"Pente maximale","value":"12-14%, seulement par moments"},{"label":"Pavage des sentiers","value":"b\u00e9ton"},{"label":"Toilettes","value":"oui, au bar restaurant - \u00e9quip\u00e9"},{"label":"Panneaux d'orientation ou d'information","value":"oui"},{"label":"Pr\u00e9sence d'arbres ou de zones d'ombre","value":""},{"label":"Fontaines d'eau potable","value":""}],"tcm_content":[{"acf_fc_layout":"text","text":"<h2><span style=\"font-weight: 400;\">Itin\u00e9raire accessible<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Aux Colli San Fermo, vous trouverez un <\/span><b>sentier en boucle <\/b><span style=\"font-weight: 400;\">con\u00e7u pour r\u00e9pondre aux besoins des personnes handicap\u00e9es et des personnes ayant des besoins particuliers, un sentier <\/span><b>qui vous m\u00e8nera au centre du panorama.<\/b><span style=\"font-weight: 400;\">.<br \/>\nSul solido tracciato in calcestruzzo del sentiero, preceduto da un cartello informativo sui dispositivi adatti a percorrerlo, potrai procedere in sicurezza e vivere appieno la montagna bergamasca. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;itin\u00e9raire a \u00e9t\u00e9 rendu possible gr\u00e2ce \u00e0 l&#8217;initiative  <\/span><i><span style=\"font-weight: 400;\">WalkOrobie.<br \/>\nDans les montagnes ensemble avec un pas diff\u00e9rent <\/span><\/i><span style=\"font-weight: 400;\">  (2019) et le projet S.T.A.I. (2023), en collaboration avec l&#8217;IPE de Bergame.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">S.T.A.I. &#8211; Services for Accessible and Inclusive Tourism &#8211; est un projet financ\u00e9 par la Pr\u00e9sidence du Conseil des ministres et la R\u00e9gion Lombardie, dans le but de proposer un mod\u00e8le de tourisme inclusif \u00e0 d\u00e9velopper dans les territoires lacustres et montagneux de Bergame et de Brescia.<\/span><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"\u00c9tape 1 - vers la terrasse panoramique"},"tcm_ui":[{"label":"L'heure","value":"10'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p><span style=\"font-weight: 400;\">En partant de la commune de Grone, vous atteindrez en 20 minutes environ <\/span><b>Piazzale Virgo Fidelis<\/b><span style=\"font-weight: 400;\">L&#8217;h\u00f4tel est situ\u00e9 dans les collines de Berzo San Fermo, au milieu de verts p\u00e2turages, d&#8217;un petit lac et d&#8217;une piste de bobsleigh en \u00e9t\u00e9.<br \/>\nUn grand parking gratuit est disponible sur le site. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour commencer l&#8217;itin\u00e9raire, restez sur le c\u00f4t\u00e9 de la petite chapelle Virgo Fidelis. <\/span><b>Chapelle Virgo Fidelis<\/b><span style=\"font-weight: 400;\">Prenez la Via della Neve et passez devant l&#8217;\u00e9tang, qui reste sur votre droite.<br \/>\nContinuez tout droit en passant devant le restaurant et, apr\u00e8s environ 600 m, vous trouverez un sentier pav\u00e9 sur la droite qui monte un peu dans la prairie. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le chemin m\u00e8ne \u00e0 la <\/span><b>terrasse panoramique<\/b><span style=\"font-weight: 400;\">d&#8217;o\u00f9 vous jouirez d&#8217;une vue imprenable et o\u00f9, gr\u00e2ce au panneau explicatif, vous pourrez d\u00e9couvrir l&#8217;identit\u00e9 des magnifiques montagnes environnantes.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-37773\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB179-Paolo-Ardiani-1024x685.jpg\" alt=\"\" width=\"1024\" height=\"685\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB179-Paolo-Ardiani-1024x685.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB179-Paolo-Ardiani-300x201.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB179-Paolo-Ardiani-768x514.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB179-Paolo-Ardiani-1536x1028.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB179-Paolo-Ardiani-2048x1371.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"\u00c9tape 2 - Aller-retour au Banc des G\u00e9ants"},"tcm_ui":[{"label":"L'heure","value":"20'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p><span style=\"font-weight: 400;\">Pour continuer sur le chemin, quittez la terrasse du c\u00f4t\u00e9 oppos\u00e9 et suivez le sentier qui s&#8217;incurve lentement vers la droite.<br \/>\nIci, apr\u00e8s environ 200 m, vous pouvez choisir de tourner \u00e0 gauche et de monter jusqu&#8217;\u00e0 la terrasse.   <\/span><b>Banc des G\u00e9ants<\/b><span style=\"font-weight: 400;\"> (n\u00b0 97 du circuit) pour un panorama encore plus majestueux, ou continuez sur l&#8217;itin\u00e9raire principal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s une centaine de m\u00e8tres, le sentier s&#8217;infl\u00e9chit vers la droite et entame une lente descente \u00e0 travers les pr\u00e9s et les bois.<br \/>\nApr\u00e8s 400 m, vous serez de retour sur le Piazzale Virgo Fidelis, en passant de l&#8217;autre c\u00f4t\u00e9 du petit lac et de l&#8217;h\u00e9liport, et vous pourrez d\u00e9cider de la suite \u00e0 donner \u00e0 votre visite de la Val Cavallina. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-37779\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Schermata-2024-06-05-alle-17.33.57-1024x434.png\" alt=\"\" width=\"1024\" height=\"434\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Schermata-2024-06-05-alle-17.33.57-1024x434.png 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Schermata-2024-06-05-alle-17.33.57-300x127.png 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Schermata-2024-06-05-alle-17.33.57-768x325.png 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Schermata-2024-06-05-alle-17.33.57-1536x651.png 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Schermata-2024-06-05-alle-17.33.57-2048x868.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]}],"slides":[{"image":{"ID":37759,"id":37759,"title":"Val_Cavallina_Colli_San_Fermo_Grone_TB177 [Paolo Ardiani]","filename":"Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-scaled.jpg","filesize":553479,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/itineraire-vers-le-belvedere-des-collines-de-san-fermo\/val_cavallina_colli_san_fermo_grone_tb177-paolo-ardiani-2\/","alt":"","author":"8","description":"","caption":"","name":"val_cavallina_colli_san_fermo_grone_tb177-paolo-ardiani-2","status":"inherit","uploaded_to":84920,"date":"2024-06-05 14:25:07","modified":"2024-10-07 09:07:10","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":991,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-2048x793.jpg","2048x2048-width":2048,"2048x2048-height":793,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Val_Cavallina_Colli_San_Fermo_Grone_TB177-Paolo-Ardiani-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto_layout":"scroll","hero_type":"images","hero_title":"Itin\u00e9raire vers le Belv\u00e9d\u00e8re des collines de San Fermo","hero_text":"<p>          <i><br \/>\n            <span style=\"font-weight: 400;\">Informations sur l&#8217;accessibilit\u00e9<\/span><br \/>\n          <\/i><\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_buttons_group":{"buttons":false},"filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"hero_buttons":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/84920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/84920\/revisions"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=84920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=84920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=84920"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=84920"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=84920"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=84920"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=84920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}