{"id":99656,"date":"2025-05-12T11:14:03","date_gmt":"2025-05-12T09:14:03","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/azienda-agricola-castello-degli-angeli-2\/"},"modified":"2025-05-12T10:25:12","modified_gmt":"2025-05-12T08:25:12","slug":"azienda-agricola-castello-degli-angeli","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/azienda-agricola-castello-degli-angeli\/","title":{"rendered":"Azienda Agricola Castello degli Angeli"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":101450,"template":"","categories":[851],"tags":[],"aggr":[],"area":[907],"kind":[18719],"zona":[],"class_list":["post-99656","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-manger","area-carobbio-degli-angeli","kind-ristorante-fr"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Azienda Agricola Castello degli Angeli","hero_text":"","slides":[{"image":{"ID":101450,"id":101450,"title":"Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","filename":"Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","filesize":316806,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/azienda-agricola-castello-degli-angeli\/castello-degli-angeli_sala-affreschi_sale-interne_ktrtuzjw-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"castello-degli-angeli_sala-affreschi_sale-interne_ktrtuzjw-jpg-2","status":"inherit","uploaded_to":99656,"date":"2024-11-12 13:12:46","modified":"2025-05-12 08:25:12","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","2048x2048-width":1620,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/Castello-degli-Angeli_Sala-Affreschi_Sale-Interne_ktrtuzjw.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Azienda Agricola Castello degli Angeli","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Demeure d&#8217;\u00e9motions.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.6698131","longitude":"9.8330199","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Scalette","iu_addr_postalcode":"24060","iu_addr_city":"Carobbio degli Angeli","iu_addr_province":"Carobbio degli Angeli","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"info@castellodegliangeli.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":true,"iu_takeaway":true,"iu_delivery":true,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"67","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/99656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/99656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/101450"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=99656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=99656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=99656"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=99656"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=99656"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=99656"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=99656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}