{"id":181375,"date":"2025-04-18T13:06:12","date_gmt":"2025-04-18T11:06:12","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/hotel-resort-spa-miramonti\/"},"modified":"2025-04-18T16:30:36","modified_gmt":"2025-04-18T14:30:36","slug":"hotel-resort-spa-miramonti","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/","title":{"rendered":"Hotel Resort &amp; Spa Miramonti"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":150213,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-181375","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":150213,"id":150213,"title":"ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","filename":"ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","filesize":657999,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:25","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":715,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-300x136.jpg","medium-width":300,"medium-height":136,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-768x348.jpg","medium_large-width":768,"medium_large-height":348,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-1024x463.jpg","large-width":1024,"large-height":463,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57-1536x695.jpg","1536x1536-width":1536,"1536x1536-height":695,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","2048x2048-width":1580,"2048x2048-height":715,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":136,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":181,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca77737e856a5687c8ef7c469ccb11ba_a8b72e57.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":272}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150220,"id":150220,"title":"be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","filename":"be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","filesize":253461,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:26","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":685,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-300x130.jpg","medium-width":300,"medium-height":130,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-768x333.jpg","medium_large-width":768,"medium_large-height":333,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-1024x444.jpg","large-width":1024,"large-height":444,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d-1536x666.jpg","1536x1536-width":1536,"1536x1536-height":666,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","2048x2048-width":1580,"2048x2048-height":685,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":130,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":173,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/be9ecfdb6137ea2fea9c4f037c23810f_aec2181d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":260}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150227,"id":150227,"title":"69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","filename":"69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","filesize":413346,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/69d1663a54734c1ec8cff3059e194350_adf00f8e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"69d1663a54734c1ec8cff3059e194350_adf00f8e-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:27","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":624,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e-300x118.jpg","medium-width":300,"medium-height":118,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e-768x303.jpg","medium_large-width":768,"medium_large-height":303,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e-1024x404.jpg","large-width":1024,"large-height":404,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e-1536x607.jpg","1536x1536-width":1536,"1536x1536-height":607,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","2048x2048-width":1580,"2048x2048-height":624,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":118,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":158,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/69d1663a54734c1ec8cff3059e194350_adf00f8e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":237}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150234,"id":150234,"title":"422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","filename":"422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","filesize":388675,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:28","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":608,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-300x115.jpg","medium-width":300,"medium-height":115,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-768x296.jpg","medium_large-width":768,"medium_large-height":296,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-1024x394.jpg","large-width":1024,"large-height":394,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410-1536x591.jpg","1536x1536-width":1536,"1536x1536-height":591,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","2048x2048-width":1580,"2048x2048-height":608,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":115,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/422eb9d2cc271a7ab9b35c7a0a6c3aa4_bd550410.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150241,"id":150241,"title":"b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","filename":"b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","filesize":288722,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:29","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":665,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-300x126.jpg","medium-width":300,"medium-height":126,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-768x323.jpg","medium_large-width":768,"medium_large-height":323,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-1024x431.jpg","large-width":1024,"large-height":431,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8-1536x646.jpg","1536x1536-width":1536,"1536x1536-height":646,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","2048x2048-width":1580,"2048x2048-height":665,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":126,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":168,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b75c0b4aeca8bc0867d2b77614e4df7f_a6c790a8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":253}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150248,"id":150248,"title":"14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","filename":"14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","filesize":324037,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/14bbe83841a6474adc52df4cca0310a3_237ee7d6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"14bbe83841a6474adc52df4cca0310a3_237ee7d6-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:30","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":737,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6-300x140.jpg","medium-width":300,"medium-height":140,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6-768x358.jpg","medium_large-width":768,"medium_large-height":358,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6-1024x478.jpg","large-width":1024,"large-height":478,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6-1536x716.jpg","1536x1536-width":1536,"1536x1536-height":716,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","2048x2048-width":1580,"2048x2048-height":737,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":140,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":187,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14bbe83841a6474adc52df4cca0310a3_237ee7d6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":280}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150255,"id":150255,"title":"a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","filename":"a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","filesize":331579,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a3b93dac050e6085f0a7419df8f2bc2a_896064c2-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:31","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":614,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2-300x117.jpg","medium-width":300,"medium-height":117,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2-768x298.jpg","medium_large-width":768,"medium_large-height":298,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2-1024x398.jpg","large-width":1024,"large-height":398,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2-1536x597.jpg","1536x1536-width":1536,"1536x1536-height":597,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","2048x2048-width":1580,"2048x2048-height":614,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":117,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a3b93dac050e6085f0a7419df8f2bc2a_896064c2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":233}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150262,"id":150262,"title":"b091c806ea366a4ed622734df166b511_0366bdd7.jpg","filename":"b091c806ea366a4ed622734df166b511_0366bdd7.jpg","filesize":546627,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/b091c806ea366a4ed622734df166b511_0366bdd7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b091c806ea366a4ed622734df166b511_0366bdd7-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:32","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":719,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7-300x137.jpg","medium-width":300,"medium-height":137,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7-768x349.jpg","medium_large-width":768,"medium_large-height":349,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7-1024x466.jpg","large-width":1024,"large-height":466,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7-1536x699.jpg","1536x1536-width":1536,"1536x1536-height":699,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7.jpg","2048x2048-width":1580,"2048x2048-height":719,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":137,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":182,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b091c806ea366a4ed622734df166b511_0366bdd7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":273}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150269,"id":150269,"title":"c68bebd560429c4cee2db6d721254240_abfbc088.jpg","filename":"c68bebd560429c4cee2db6d721254240_abfbc088.jpg","filesize":434078,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/c68bebd560429c4cee2db6d721254240_abfbc088-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c68bebd560429c4cee2db6d721254240_abfbc088-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:33","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":754,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088-300x143.jpg","medium-width":300,"medium-height":143,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088-768x367.jpg","medium_large-width":768,"medium_large-height":367,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088-1024x489.jpg","large-width":1024,"large-height":489,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088-1536x733.jpg","1536x1536-width":1536,"1536x1536-height":733,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088.jpg","2048x2048-width":1580,"2048x2048-height":754,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":143,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":191,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c68bebd560429c4cee2db6d721254240_abfbc088.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":286}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150276,"id":150276,"title":"6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","filename":"6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","filesize":161071,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6f9581d4200de8ca423f63a38223b53f_b35d8ffc-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:34","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f9581d4200de8ca423f63a38223b53f_b35d8ffc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150283,"id":150283,"title":"040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","filename":"040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","filesize":218339,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"040f8a878937a57bff278b3429ee3a8c_b27d4bc4-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:35","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/040f8a878937a57bff278b3429ee3a8c_b27d4bc4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150290,"id":150290,"title":"b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","filename":"b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","filesize":371208,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-resort-spa-miramonti\/b5717df7f5e6c8907d6872e068139509_dafd7ced-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b5717df7f5e6c8907d6872e068139509_dafd7ced-jpg-2","status":"inherit","uploaded_to":181375,"date":"2025-04-17 14:45:36","modified":"2025-04-18 14:29:46","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b5717df7f5e6c8907d6872e068139509_dafd7ced.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.826596","longitude":"9.511280","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"24038","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39035868000","iu_cell":"","iu_email":"info@hotelmiramontibergamo.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"4627","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","id_eppen":"","hours":"","accessibilityicons":[],"url":"","description":"<p>Hotel Resort &#038; SPA Miramonti, z widokiem na naturalny balkon doliny Imagna, zosta\u0142 niedawno odnowiony i oferuje nowoczesn\u0105 i komfortow\u0105 struktur\u0119, jasne pokoje we wsp\u00f3\u0142czesnym stylu, ekskluzywne centrum odnowy biologicznej Bio Spa Car\u00e9ra oraz restauracj\u0119 Gritti serwuj\u0105c\u0105 tradycyjne dania z Bergamo.  <\/p>\n","hero_title":"Hotel Resort & Spa Miramonti","hero_text":"<p>Od ponad 40 lat jest gwarancj\u0105 wysokiej jako\u015bci zakwaterowania turystycznego w Dolinie G\u00f3rnej Imagny, idealnego dla tych, kt\u00f3rzy chc\u0105 zregenerowa\u0107 si\u0142y, relaksuj\u0105c si\u0119 lub uprawiaj\u0105c sport na \u0142onie natury.<\/p>\n","indepth":"<p>Hotel oferuje go\u015bciom 35 nowoczesnych i komfortowych pokoi z widokiem na dolin\u0119, wyposa\u017conych w balkon, 27-calowy telewizor LCD, telefon, sejf, dost\u0119p do Internetu WIFI, \u0142azienk\u0119 z prysznicem, suszark\u0119 do w\u0142os\u00f3w, szlafrok i r\u0119cznik k\u0105pielowy dost\u0119pne przez ca\u0142y pobyt.<br \/>\nWewn\u0105trz hotelu znajduje si\u0119 prawdziwa oaza dobrego samopoczucia, Bio spa Car\u00e8ra, stworzone w celu przywr\u00f3cenia energii witalnej duchowi i cia\u0142u poprzez naturalne dobre samopoczucie. W nowych i ekskluzywnych pokojach, wysokiej jako\u015bci zabiegi, wyspecjalizowany personel i staranny dob\u00f3r organicznych kosmetyk\u00f3w, panoramiczny podgrzewany kryty i odkryty basen z hydromasa\u017cem i wodospadem szyjnym. <\/p>\n","howtogetthere":"<p>Z autostrady A4 nale\u017cy zjecha\u0107 na Dalmine i kierowa\u0107 si\u0119 na Valle Brembana do Alm\u00e8. Na rondzie Alm\u00e8 zjed\u017a ostatnim zjazdem w kierunku Valle Imagna i jed\u017a dalej do S. Omobono Terme, a nast\u0119pnie Rota d&#8217;Imagna.<br \/>\nNajbli\u017csze lotniska to Orio al Serio (25 km), Mediolan Linate (55 km) lub Mediolan Malpensa (120 km). Poci\u0105gi IC i EC zatrzymuj\u0105 si\u0119 w Bergamo lub Ponte San Pietro.  <\/p>\n","iu_addr_streetnumber":"Via Alle Fonti, 5\/6","iu_website":"http:\/\/www.hotelmiramontibergamo.com","iu_company_name":"Hotel Gritti Sas di Gritti Adelia e Olimpia","iu_vat":"","iu_stars":"4","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"<p>Accesso alla Bio-Spa Car\u00e9ra dalle 10:00 alle 20:00.&#13;<br \/>\nLa chiusura annuale della struttura viene comunicata sul sito web e pagina facebook.<\/p>\n","registered_office":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"safe","label":"safe"},{"value":"health_club","label":"Centro benessere"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"laundry","label":"Lavanderia"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"pool","label":"Piscina"},{"value":"restaurant","label":"Ristorante"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"tv_lounge","label":"Sala TV"},{"value":"sauna","label":"Sauna"},{"value":"solarium","label":"Solarium"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms_with_tub","label":"Bagni con idromassaggio"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/181375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/181375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/150213"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=181375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=181375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=181375"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=181375"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=181375"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=181375"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=181375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}