{"id":181653,"date":"2025-04-18T13:27:27","date_gmt":"2025-04-18T11:27:27","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/berganest\/"},"modified":"2025-04-18T13:27:27","modified_gmt":"2025-04-18T11:27:27","slug":"berganest","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/berganest\/","title":{"rendered":"BergaNest"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":165009,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-181653","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":165009,"id":165009,"title":"21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","filename":"21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","filesize":462186,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/berganest\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"21b08528fa2e4e854e0d5ff8989f15ae_df3255ba-jpg-2","status":"inherit","uploaded_to":181653,"date":"2025-04-18 08:50:01","modified":"2025-04-18 14:37:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":960,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","1536x1536-width":960,"1536x1536-height":1280,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","2048x2048-width":960,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/21b08528fa2e4e854e0d5ff8989f15ae_df3255ba.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165016,"id":165016,"title":"14a63c3bd72807d3e9a42580a197f1cd_85be1cbc.jpg","filename":"14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-scaled.jpg","filesize":423250,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/berganest\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-jpg-2","status":"inherit","uploaded_to":181653,"date":"2025-04-18 08:50:02","modified":"2025-04-18 14:37:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/14a63c3bd72807d3e9a42580a197f1cd_85be1cbc-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165023,"id":165023,"title":"d65cc850dc073b739b36cb35e5e92f3c_fabe15bc.jpg","filename":"d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-scaled.jpg","filesize":637973,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/berganest\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-jpg-2","status":"inherit","uploaded_to":181653,"date":"2025-04-18 08:50:05","modified":"2025-04-18 14:37:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d65cc850dc073b739b36cb35e5e92f3c_fabe15bc-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165030,"id":165030,"title":"6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","filename":"6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","filesize":833415,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/berganest\/6acf1c869f2d35515602697966e2b236_6acd91f2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6acf1c869f2d35515602697966e2b236_6acd91f2-jpg-2","status":"inherit","uploaded_to":181653,"date":"2025-04-18 08:50:07","modified":"2025-04-18 14:37:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1536,"height":2049,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2-768x1025.jpg","medium_large-width":768,"medium_large-height":1025,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2-1151x1536.jpg","1536x1536-width":1151,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","2048x2048-width":1535,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6acf1c869f2d35515602697966e2b236_6acd91f2.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_layout":"","filotto_fill":"","button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.706417","longitude":"9.655807","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":false,"iu_shortprice":"","iu_addr_postalcode":"24128","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"+39 340 8654184","iu_email":"robertoiannucci83@gmail.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"11162","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","only_ambassadors":false,"id_eppen":"","hours":"","accessibilityicons":[],"description":"<p>Tu\u017c obok G\u00f3rnego Miasta i mur\u00f3w weneckich, ze spektakularnym widokiem, mieszkanie znajduje si\u0119 w XVIII-wiecznym budynku, zachowuj\u0105c swoje oryginalne cechy.<br \/>\nDwupokojowy apartament z zapieraj\u0105cym dech w piersiach widokiem i w pe\u0142ni wyposa\u017cony. Mo\u017ce pomie\u015bci\u0107 do czterech os\u00f3b.<br \/>\nDu\u017ca sypialnia z podw\u00f3jnym \u0142\u00f3\u017ckiem i biurkiem; dwa dodatkowe \u0142\u00f3\u017cka dost\u0119pne w salonie. St\u00f3\u0142 i niedawno odnowiona kuchnia.  <\/p>\n","hero_title":"BergaNest","hero_text":"<p>Tw\u00f3j przytulny dom w Bergamo<\/p>\n<p>CIN: EN016024C2Z3QCAV2N<\/p>\n","indepth":"<p>WASI GO\u015aCIE: Alessia i Davide<br \/>\nFilantropi z zawodu, podr\u00f3\u017cnicy z zami\u0142owania. Przez ostatnie 15 lat mieszkali\u015bmy w Azji \u015arodkowej, na Bliskim Wschodzie i w Norwegii. Obecnie mieszkamy w Ammanie w Jordanii.<br \/>\nBergaNest urz\u0105dzili\u015bmy meblami z kraj\u00f3w, w kt\u00f3rych mieszkali\u015bmy, dzi\u0119ki czemu jest to przytulne miejsce, do kt\u00f3rego chce si\u0119 wraca\u0107. Mamy nadziej\u0119, \u017ce znajdziesz tu miejsce, by odpocz\u0105\u0107 i cieszy\u0107 si\u0119 \u017cyciem.<br \/>\nTW\u00d3J wsp\u00f3\u0142gospodarz: Roberto<br \/>\nPoniewa\u017c mieszkamy za granic\u0105,<br \/>\nRoberto b\u0119dzie Twoim gospodarzem w Bergamo.<br \/>\nPunkrockowy filozof, piwowar-samouk, biegacz z przerwami, entuzjasta historii i nauki.<br \/>\nCzasami siedzi i my\u015bli, a czasami po prostu siedzi.   <\/p>\n","howtogetthere":"<p>Z lotniska Orio al Serio nale\u017cy wsi\u0105\u015b\u0107 do autobusu nr 1A i wysi\u0105\u015b\u0107 na przystanku Colle Aperto. Przystanek oddalony jest od obiektu o 2 minuty spacerem. Go\u015bcie podr\u00f3\u017cuj\u0105cy samochodem mog\u0105 skorzysta\u0107 z pobliskiego p\u0142atnego parkingu.  <\/p>\n","iu_addr_streetnumber":"Via Borgo Canale, 22","iu_website":"https:\/\/maps.app.goo.gl\/5BWd2H64Y5mDBpiX6","url":"","time":"","service_icons":[],"iu_company_name":"Alessia Locarini","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","registered_office":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/181653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/181653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/165009"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=181653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=181653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=181653"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=181653"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=181653"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=181653"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=181653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}