{"id":182197,"date":"2025-04-18T13:24:07","date_gmt":"2025-04-18T11:24:07","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/biblioteka\/"},"modified":"2025-04-18T16:48:32","modified_gmt":"2025-04-18T14:48:32","slug":"biblioteka","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/","title":{"rendered":"Biblioteka"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":162409,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-182197","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":162409,"id":162409,"title":"6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","filename":"6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","filesize":541665,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:26","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":700,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-300x135.jpg","medium-width":300,"medium-height":135,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-768x345.jpg","medium_large-width":768,"medium_large-height":345,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-1024x459.jpg","large-width":1024,"large-height":459,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0-1536x689.jpg","1536x1536-width":1536,"1536x1536-height":689,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","2048x2048-width":1560,"2048x2048-height":700,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":135,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":179,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6c99bfcb3ccc821c07917bc44da34a0a_e59804e0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":269}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162416,"id":162416,"title":"6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c.jpg","filename":"6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-scaled.jpg","filesize":976789,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:27","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":2296,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-300x269.jpg","medium-width":300,"medium-height":269,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-768x689.jpg","medium_large-width":768,"medium_large-height":689,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-1024x918.jpg","large-width":1024,"large-height":918,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-1536x1378.jpg","1536x1536-width":1536,"1536x1536-height":1378,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-2048x1837.jpg","2048x2048-width":2048,"2048x2048-height":1837,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":269,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":359,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eeef26a69dad7c85b4db5f8caa718a2_854a7e4c-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":538}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162423,"id":162423,"title":"ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","filename":"ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","filesize":135706,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/ec0d1361d30be9764a410baf6caaefc8_150e20f9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec0d1361d30be9764a410baf6caaefc8_150e20f9-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:30","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec0d1361d30be9764a410baf6caaefc8_150e20f9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162430,"id":162430,"title":"d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","filename":"d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","filesize":150186,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/d7123dff371da50d64d7595a1b87b997_0f0c6991-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d7123dff371da50d64d7595a1b87b997_0f0c6991-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:31","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7123dff371da50d64d7595a1b87b997_0f0c6991.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162437,"id":162437,"title":"155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","filename":"155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","filesize":217130,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/155aead11fe19aadd0f668cf1659711a_85f84abd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"155aead11fe19aadd0f668cf1659711a_85f84abd-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:32","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":700,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd-300x135.jpg","medium-width":300,"medium-height":135,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd-768x345.jpg","medium_large-width":768,"medium_large-height":345,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd-1024x459.jpg","large-width":1024,"large-height":459,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd-1536x689.jpg","1536x1536-width":1536,"1536x1536-height":689,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","2048x2048-width":1560,"2048x2048-height":700,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":135,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":179,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/155aead11fe19aadd0f668cf1659711a_85f84abd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":269}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162444,"id":162444,"title":"e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","filename":"e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","filesize":217783,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/e99589402a6067beb8e7a47e6d8fdb68_49646db7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e99589402a6067beb8e7a47e6d8fdb68_49646db7-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:33","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":700,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7-300x135.jpg","medium-width":300,"medium-height":135,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7-768x345.jpg","medium_large-width":768,"medium_large-height":345,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7-1024x459.jpg","large-width":1024,"large-height":459,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7-1536x689.jpg","1536x1536-width":1536,"1536x1536-height":689,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","2048x2048-width":1560,"2048x2048-height":700,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":135,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":179,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99589402a6067beb8e7a47e6d8fdb68_49646db7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":269}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162451,"id":162451,"title":"ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","filename":"ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","filesize":84534,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/ec045f62740f88f379ff1993234b96ee_f34878a4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec045f62740f88f379ff1993234b96ee_f34878a4-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:34","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec045f62740f88f379ff1993234b96ee_f34878a4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162458,"id":162458,"title":"7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","filename":"7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","filesize":105273,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/7e59b55840239725a4e8b6c3353c43bb_098d5a46-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7e59b55840239725a4e8b6c3353c43bb_098d5a46-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:35","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e59b55840239725a4e8b6c3353c43bb_098d5a46.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162465,"id":162465,"title":"f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","filename":"f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","filesize":127474,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:36","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f49d7f58907c0ad31bc70c56f913d9aa_a0fa855c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":162472,"id":162472,"title":"185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","filename":"185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","filesize":74048,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/biblioteka\/185dfd18b88ccccda736820afeac5b45_f2adf9f4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"185dfd18b88ccccda736820afeac5b45_f2adf9f4-jpg-2","status":"inherit","uploaded_to":182197,"date":"2025-04-18 08:37:36","modified":"2025-04-18 14:47:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/185dfd18b88ccccda736820afeac5b45_f2adf9f4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_layout":"","filotto_fill":"","button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.705364","longitude":"9.662668","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":false,"iu_shortprice":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"335 8315712","iu_cell":"335 8315712","iu_email":"thelibrary.bergamo@gmail.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"10629","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","only_ambassadors":false,"id_eppen":"","hours":"","accessibilityicons":[],"url":"","description":"<p>Spanie w\u015br\u00f3d ksi\u0105\u017cek i sufit\u00f3w pokrytych freskami. Biblioteka, pierwotnie prywatna, staje si\u0119 urocz\u0105 otwart\u0105 przestrzeni\u0105. Urz\u0105dzona z dba\u0142o\u015bci\u0105 o oryginalne otoczenie, oferuje wygodn\u0105 dwuosobow\u0105 sof\u0119, du\u017ce biurko, nowoczesn\u0105 kuchenk\u0119 indukcyjn\u0105, wygodn\u0105 \u0142azienk\u0119 i wygodn\u0105 garderob\u0119. Znajduje si\u0119 na parterze, w dogodnej lokalizacji dwie minuty od Piazza Vecchia, serca g\u00f3rnego miasta z klubami, sklepami i restauracjami. CIR 016024-CNI-00669    <\/p>\n","hero_title":"Biblioteka","hero_text":"<p>Zaledwie rzut kamieniem od Piazza Vecchia, w samym sercu g\u00f3rnego Bergamo, ta prywatna biblioteka, przekszta\u0142cona w urocz\u0105 otwart\u0105 przestrze\u0144, zaprasza do odkrywania cud\u00f3w tego czaruj\u0105cego miasteczka.<\/p>\n","howtogetthere":"<p>&#8211; Je\u015bli przyje\u017cd\u017casz autobusem LINEA 1 z lotniska, dworca kolejowego lub z Citt\u00e0 Bassa do Colle Aperto, musisz kierowa\u0107 si\u0119 na via della Boccola, przechodz\u0105c przez Porta del Pantano Inferiore. Z via della Boccola nale\u017cy i\u015b\u0107 prosto w kierunku via del Vagine. Na ko\u0144cu via del Vagine nale\u017cy skr\u0119ci\u0107 w prawo i znale\u017a\u0107 si\u0119 na via Tassis, numer 4 znajduje si\u0119 po prawej stronie prawie na pocz\u0105tku ulicy (oko\u0142o 5 minut pieszo).<br \/>\n&#8211; Je\u015bli przyje\u017cd\u017casz LA FUNICOLARE z Piazzetta Angelini, id\u017a do Via Gombito, id\u017a ni\u0105 przez 400 metr\u00f3w, znajdziesz sklepy, restauracje, bary, wkr\u00f3tce za Piazza Vecchia (kt\u00f3ry jest po lewej stronie), kontynuuj Via Gombito i drug\u0105 ulic\u0105 po prawej stronie jest Via Tassis. Numer 4 znajduje si\u0119 po lewej stronie (oko\u0142o 6 minut spacerem).<br \/>\n&#8211; Je\u015bli przyje\u017cd\u017casz SAMOCHODEM z parkingu San Pancrazio (gdzie mo\u017cna uzyska\u0107 dzienn\u0105 stawk\u0119) z Via Mercato del Fieno, skr\u0119\u0107 w prawo w Via San Lorenzo. Po 110 metrach skr\u0119\u0107 w lewo w via Tassis i id\u017a ni\u0105 do punktu nr 4 (oko\u0142o 5 minut pieszo). <\/p>\n","iu_addr_streetnumber":"Via Tassis, 4","time":"","iu_company_name":"Monica Moretti","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","registered_office":"","service_icons":[{"value":"safe","label":"safe"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182197\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/162409"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=182197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=182197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=182197"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=182197"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=182197"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=182197"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=182197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}