{"id":182211,"date":"2025-04-18T13:24:39","date_gmt":"2025-04-18T11:24:39","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bramantesco\/"},"modified":"2025-04-28T22:49:21","modified_gmt":"2025-04-28T20:49:21","slug":"bramantesco","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/","title":{"rendered":"Bramantesco"},"excerpt":{"rendered":"","protected":false},"author":48,"featured_media":163469,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-182211","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":163469,"id":163469,"title":"8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a","filename":"8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","filesize":64784,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a-2\/","alt":"","author":"0","description":"","caption":"","name":"8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a-2","status":"inherit","uploaded_to":182211,"date":"2025-04-18 08:42:47","modified":"2025-04-18 14:48:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":600,"height":450,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","medium_large-width":600,"medium_large-height":450,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","large-width":600,"large-height":450,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","1536x1536-width":600,"1536x1536-height":450,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","2048x2048-width":600,"2048x2048-height":450,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8f8fd32a13bdb21bb9d21b76ac421c6c_85f5ec2a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163476,"id":163476,"title":"8fcab5aceb128d313c71ac1f86dafd98_c90a6d57","filename":"8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-scaled.jpg","filesize":589785,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-2\/","alt":"","author":"0","description":"","caption":"","name":"8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-2","status":"inherit","uploaded_to":182211,"date":"2025-04-18 08:42:47","modified":"2025-04-18 14:48:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fcab5aceb128d313c71ac1f86dafd98_c90a6d57-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163483,"id":163483,"title":"de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c","filename":"de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-scaled.jpg","filesize":670051,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-2\/","alt":"","author":"0","description":"","caption":"","name":"de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-2","status":"inherit","uploaded_to":182211,"date":"2025-04-18 08:42:50","modified":"2025-04-18 14:48:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de32fe7dfcfb6fd9ec131440e8bd40f4_f9e4e35c-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163490,"id":163490,"title":"738470a5512428a6133b200f81d205d0_2adad4c9","filename":"738470a5512428a6133b200f81d205d0_2adad4c9.jpg","filesize":62331,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/738470a5512428a6133b200f81d205d0_2adad4c9-2\/","alt":"","author":"0","description":"","caption":"","name":"738470a5512428a6133b200f81d205d0_2adad4c9-2","status":"inherit","uploaded_to":182211,"date":"2025-04-18 08:42:53","modified":"2025-04-18 14:48:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":600,"height":450,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","medium_large-width":600,"medium_large-height":450,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","large-width":600,"large-height":450,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","1536x1536-width":600,"1536x1536-height":450,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","2048x2048-width":600,"2048x2048-height":450,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/738470a5512428a6133b200f81d205d0_2adad4c9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163497,"id":163497,"title":"09bb08acf3e3073e24390d6988450209_c90a6d57","filename":"09bb08acf3e3073e24390d6988450209_c90a6d57-scaled.jpg","filesize":589785,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/09bb08acf3e3073e24390d6988450209_c90a6d57-2\/","alt":"","author":"0","description":"","caption":"","name":"09bb08acf3e3073e24390d6988450209_c90a6d57-2","status":"inherit","uploaded_to":182211,"date":"2025-04-18 08:42:53","modified":"2025-04-18 14:48:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09bb08acf3e3073e24390d6988450209_c90a6d57-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163504,"id":163504,"title":"9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25","filename":"9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-scaled.jpg","filesize":347933,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bramantesco\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-2\/","alt":"","author":"0","description":"","caption":"","name":"9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-2","status":"inherit","uploaded_to":182211,"date":"2025-04-18 08:42:56","modified":"2025-04-18 14:48:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9df3c3ef6b8ab576ead9c5fe59a1cc8e_ac4a4f25-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_layout":"","filotto_fill":"","button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.702688","longitude":"9.672533","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":false,"iu_shortprice":"","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3331319041","iu_cell":"+393331319041","iu_email":"dmrcase@gmail.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"5773","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","only_ambassadors":false,"id_eppen":"","hours":"","accessibilityicons":[],"url":"","description":"<p>Ten zabytkowy budynek z 1527 roku zdobi\u0105 oryginalne freski w stylu malarza Lorenzo Lotto. Obiekt po\u0142o\u017cony jest w centrum Bergamo i oferuje nowocze\u015bnie urz\u0105dzone studio na antresoli z bezp\u0142atnym WiFi we wszystkich pomieszczeniach. Do dyspozycji Go\u015bci jest aneks kuchenny, jadalnia oraz cz\u0119\u015b\u0107 wypoczynkowa z sof\u0105 i telewizorem z p\u0142askim ekranem. W \u0142azience znajduje si\u0119 prysznic, zestaw kosmetyk\u00f3w i suszarka do w\u0142os\u00f3w. Obiekt Bramantesco oddalony jest o 5 km od zjazdu z autostrady A4 w Bergamo. Dojazd na lotnisko Bergamo Orio al Serio zajmuje 15 minut.     <\/p>\n","hero_title":"Bramantesco","hero_text":"<p><span style=\"font-size: small;\"> <\/span><\/p>\n","price":"<p>Od 60,00 do 100,00 euro<\/p>\n","iu_addr_streetnumber":"Via Pignolo 112","iu_company_name":"BIZIOLI LEGNO SRL","iu_vat":"","iu_stars":"","iu_rooms":"1","iu_beds":"3","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"<p>Check-in 14:00 \/ 19:00<\/p>\n","registered_office":"","service_icons":[{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/users\/48"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/163469"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=182211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=182211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=182211"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=182211"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=182211"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=182211"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=182211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}