{"id":182330,"date":"2025-04-18T13:26:03","date_gmt":"2025-04-18T11:26:03","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/hotel-residence-la-rosa\/"},"modified":"2025-04-18T16:50:37","modified_gmt":"2025-04-18T14:50:37","slug":"hotel-residence-la-rosa","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-residence-la-rosa\/","title":{"rendered":"Hotel Residence La Rosa"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":164026,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-182330","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":164026,"id":164026,"title":"260b1bbf4edb9ebda775badc90577d37_f8e833ba.jpg","filename":"260b1bbf4edb9ebda775badc90577d37_f8e833ba-scaled.jpg","filesize":689317,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-residence-la-rosa\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"260b1bbf4edb9ebda775badc90577d37_f8e833ba-jpg-2","status":"inherit","uploaded_to":182330,"date":"2025-04-18 08:45:54","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/260b1bbf4edb9ebda775badc90577d37_f8e833ba-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164033,"id":164033,"title":"36bdfc6681a8635d63cab6eeecbee385_f29b9e7d.jpg","filename":"36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-scaled.jpg","filesize":394324,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-residence-la-rosa\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-jpg-2","status":"inherit","uploaded_to":182330,"date":"2025-04-18 08:45:57","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/36bdfc6681a8635d63cab6eeecbee385_f29b9e7d-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164040,"id":164040,"title":"c558a80cffc73cd549775c2508dc503d_5e028636.jpg","filename":"c558a80cffc73cd549775c2508dc503d_5e028636.jpg","filesize":212632,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-residence-la-rosa\/c558a80cffc73cd549775c2508dc503d_5e028636-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c558a80cffc73cd549775c2508dc503d_5e028636-jpg-2","status":"inherit","uploaded_to":182330,"date":"2025-04-18 08:45:59","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c558a80cffc73cd549775c2508dc503d_5e028636.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164047,"id":164047,"title":"062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","filename":"062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","filesize":159670,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/hotel-residence-la-rosa\/062040ceda3f318fa2da9c022a79d096_a470cc08-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"062040ceda3f318fa2da9c022a79d096_a470cc08-jpg-2","status":"inherit","uploaded_to":182330,"date":"2025-04-18 08:46:00","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/062040ceda3f318fa2da9c022a79d096_a470cc08.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","function":"link","target_modal":"","latitude":"45.925160","longitude":"10.071630","accessibilitycontent":{"tcm_content":false},"gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"24020","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 034631640","iu_cell":"+39 3299545407","iu_email":"info@hotelresidencelarosa.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"7313","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","only_ambassadors":false,"id_eppen":"","hours":"","accessibilityicons":[],"url":"","description":"<p>Do dyspozycji go\u015bci: bar, czytelnia, pok\u00f3j karciany, pok\u00f3j zabaw dla dzieci z grami wideo, pi\u0142karzykami i tenisem sto\u0142owym, pok\u00f3j dzieci\u0119cy, tawerna, winda i &#8211; dla narciarzy &#8211; obszerna przechowalnia nart i but\u00f3w. Pokoje wyposa\u017cone s\u0105 w \u0142azienk\u0119, kolorowy telewizor, telefon i panoramiczny taras. W miesi\u0105cach letnich istnieje r\u00f3wnie\u017c mo\u017cliwo\u015b\u0107 skorzystania z hotelowego transferu, kt\u00f3ry pozwoli na przemieszczanie si\u0119 lub zakupy bez konieczno\u015bci parkowania samochodu.  <\/p>\n","hero_title":"Hotel Residence La Rosa","hero_text":"<p><span>Hotel Residence La Rosa po\u0142o\u017cony jest 1,5 km od centrum miejscowo\u015bci Bratto i prze\u0142\u0119czy Presolana i oferuje wszelkie udogodnienia zapewniaj\u0105ce niezapomniany pobyt.<\/span><\/p>\n","iu_addr_streetnumber":"Via Cantoniera, 20","iu_website":"http:\/\/www.hotelresidencelarosa.com","time":"","iu_company_name":"hotel residence la rosa srl","iu_vat":"03532410168","iu_stars":"3","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","structure_code":"","registered_office":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"hero_buttons":false,"startingprice":"50","gallery":{"gallery_items":false},"poi_data":{"indepth":"","price":"","time":"","latitude":"45.925160","longitude":"10.071630","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_addr_city":"Bergamo","iu_phone":"+39 034631640","iu_cell":"+39 3299545407","iu_website":"http:\/\/www.hotelresidencelarosa.com","iu_email":"info@hotelresidencelarosa.com","startingprice":"50","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"restaurant","label":"Ristorante"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"diners","label":"Diners Club"}],"services":"","parking":"","breakfast":"","restaurant":"","internet":"","children":"","pets":"","iu_company_name":"hotel residence la rosa srl","iu_vat":"03532410168","iu_stars":"3","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","id_visit_manza":"7313","cir":"016064-ALB-00005"},"featured_video":false,"is_an_ambassador":false,"video_youtube_url":"","video_vimeo_url":"","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"restaurant","label":"Ristorante"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"diners","label":"Diners Club"}],"cir":"016064-ALB-00005","hero_random_sort":false,"filotto_no_overlay":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/164026"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=182330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=182330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=182330"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=182330"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=182330"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=182330"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=182330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}