{"id":182369,"date":"2025-04-18T13:09:41","date_gmt":"2025-04-18T11:09:41","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/tree-roooms-nowoczesny-pensjonat\/"},"modified":"2025-04-18T13:09:41","modified_gmt":"2025-04-18T11:09:41","slug":"tree-roooms-nowoczesny-pensjonat","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/","title":{"rendered":"TREE ROOOMS NOWOCZESNY PENSJONAT"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":152941,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-182369","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":152941,"id":152941,"title":"9a938a873a4b3059c9b07b0237dab508_b385336a.png","filename":"9a938a873a4b3059c9b07b0237dab508_b385336a.png","filesize":674817,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a.png","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/9a938a873a4b3059c9b07b0237dab508_b385336a-png-2\/","alt":"","author":"0","description":"","caption":"","name":"9a938a873a4b3059c9b07b0237dab508_b385336a-png-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:27","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":961,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a-768x513.png","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a-1024x683.png","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a.png","1536x1536-width":1440,"1536x1536-height":961,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a.png","2048x2048-width":1440,"2048x2048-height":961,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a938a873a4b3059c9b07b0237dab508_b385336a.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152948,"id":152948,"title":"67a3ae36a04fc13374aafeb841140244_736bcd3d.png","filename":"67a3ae36a04fc13374aafeb841140244_736bcd3d.png","filesize":864847,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d.png","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/67a3ae36a04fc13374aafeb841140244_736bcd3d-png-2\/","alt":"","author":"0","description":"","caption":"","name":"67a3ae36a04fc13374aafeb841140244_736bcd3d-png-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:30","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":961,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d-768x513.png","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d-1024x683.png","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d.png","1536x1536-width":1440,"1536x1536-height":961,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d.png","2048x2048-width":1440,"2048x2048-height":961,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67a3ae36a04fc13374aafeb841140244_736bcd3d.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152955,"id":152955,"title":"7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","filename":"7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","filesize":644656,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019-png-2\/","alt":"","author":"0","description":"","caption":"","name":"7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019-png-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:33","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":961,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019-768x513.png","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019-1024x683.png","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","1536x1536-width":1440,"1536x1536-height":961,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","2048x2048-width":1440,"2048x2048-height":961,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7af6909e1b32e4c9bd51540d63b1bf4b_c58c5019.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152962,"id":152962,"title":"165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","filename":"165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","filesize":485946,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d-png-2\/","alt":"","author":"0","description":"","caption":"","name":"165fdae295f271c6f14123c1920d8f42_9dc6cd3d-png-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:35","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":801,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d-768x513.png","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d-1024x684.png","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","1536x1536-width":1200,"1536x1536-height":801,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","2048x2048-width":1200,"2048x2048-height":801,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/165fdae295f271c6f14123c1920d8f42_9dc6cd3d.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152969,"id":152969,"title":"6cf911bdd62cee0394e944526116db5e_f93b08a8.jpg","filename":"6cf911bdd62cee0394e944526116db5e_f93b08a8-scaled.jpg","filesize":383706,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/6cf911bdd62cee0394e944526116db5e_f93b08a8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6cf911bdd62cee0394e944526116db5e_f93b08a8-jpg-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:37","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1708,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cf911bdd62cee0394e944526116db5e_f93b08a8-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152976,"id":152976,"title":"961a027d1ef864eb11cafe06099dbea3_f5ba7bbf.jpg","filename":"961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-scaled.jpg","filesize":305131,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-jpg-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:39","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/961a027d1ef864eb11cafe06099dbea3_f5ba7bbf-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152983,"id":152983,"title":"b8f620db248c72fc7d1a07a400706511_d9c8c80a.jpg","filename":"b8f620db248c72fc7d1a07a400706511_d9c8c80a-scaled.jpg","filesize":318688,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b8f620db248c72fc7d1a07a400706511_d9c8c80a-jpg-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:42","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-1536x1026.jpg","1536x1536-width":1536,"1536x1536-height":1026,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b8f620db248c72fc7d1a07a400706511_d9c8c80a-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152990,"id":152990,"title":"bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6.jpg","filename":"bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-scaled.jpg","filesize":352424,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/tree-roooms-nowoczesny-pensjonat\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-jpg-2","status":"inherit","uploaded_to":182369,"date":"2025-04-17 14:56:44","modified":"2025-04-18 14:51:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bd452a6d3ff00251ce54ddab7228dd8c_46e0bbe6-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.690130","longitude":"9.672447","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+393756683842","iu_cell":"+393756683842","iu_email":"treerooms.bg@gmail.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"10797","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","id_eppen":"","hours":"","accessibilityicons":[],"description":"<p>Tree Rooms Modern Guesthouse sk\u0142ada si\u0119 z 3 przestronnych klimatyzowanych pokoi, 3 w pe\u0142ni wyposa\u017conych \u0142azienek i du\u017cej kuchni wyposa\u017conej w sprz\u0119t do przygotowywania dobrych \u015bniada\u0144 lub pysznych obiad\u00f3w i kolacji z typowymi lokalnymi produktami. Ze wzgl\u0119du na sw\u00f3j du\u017cy rozmiar, pensjonat mo\u017ce pomie\u015bci\u0107 do 10 os\u00f3b w nowoczesnych i eleganckich pokojach.<br \/>\nMieszkanie znajduje si\u0119 na trzecim pi\u0119trze z wind\u0105 w zadbanym apartamentowcu w centrum Bergamo <\/p>\n","hero_title":"TREE ROOOMS NOWOCZESNY PENSJONAT","hero_text":"<p>Tree Rooms Modern to przytulny, nowy i funkcjonalny pensjonat po\u0142o\u017cony zaledwie kilka krok\u00f3w od dworca kolejowego w Bergamo i wszystkich g\u0142\u00f3wnych us\u0142ug.<\/p>\n","indepth":"<p>W mieszkaniu obowi\u0105zuje ca\u0142kowity zakaz palenia<br \/>\nNie ma balkon\u00f3w dla pal\u0105cych, trzeba zej\u015b\u0107 na ulic\u0119.<\/p>\n","price":"<p>Cen\u0119 mo\u017cna sprawdzi\u0107 bezpo\u015brednio na stronie:<br \/>\nhttps:\/\/treeroomsguesthouse.kross.travel\/<\/p>\n","iu_addr_streetnumber":"Via Giorgio i Guido Paglia, 33","iu_website":"https:\/\/www.treeroomsbg.com\/","url":"","time":"<p>Orari check in 14.00-20.00. Dopo le 20 su disponibilit\u00e0 e tramite self check in fino alle 22.00<\/p>\n","iu_company_name":"MATTEO MARZARI","iu_vat":"04369030988","iu_stars":"","iu_rooms":"3","iu_beds":"10","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","registered_office":"","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/152941"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=182369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=182369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=182369"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=182369"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=182369"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=182369"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=182369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}