{"id":182384,"date":"2025-04-18T13:09:41","date_gmt":"2025-04-18T11:09:41","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bb-da-bice\/"},"modified":"2025-04-18T13:09:41","modified_gmt":"2025-04-18T11:09:41","slug":"bb-da-bice","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/","title":{"rendered":"B&amp;B Da Bice"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":152668,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-182384","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":152668,"id":152668,"title":"eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","filename":"eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","filesize":234842,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eb2140707945304a8bdf3994c7e5d7fe_efb4455f-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:32","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1125,"height":844,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","1536x1536-width":1125,"1536x1536-height":844,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","2048x2048-width":1125,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb2140707945304a8bdf3994c7e5d7fe_efb4455f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152675,"id":152675,"title":"844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","filename":"844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","filesize":181246,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/844b17b5fe5bd6a36e98936c9eb100df_3699153a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"844b17b5fe5bd6a36e98936c9eb100df_3699153a-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:33","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1125,"height":844,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","1536x1536-width":1125,"1536x1536-height":844,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","2048x2048-width":1125,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/844b17b5fe5bd6a36e98936c9eb100df_3699153a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152682,"id":152682,"title":"e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","filename":"e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","filesize":56152,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:34","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":840,"height":460,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596-300x164.jpg","medium-width":300,"medium-height":164,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596-768x421.jpg","medium_large-width":768,"medium_large-height":421,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","large-width":840,"large-height":460,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","1536x1536-width":840,"1536x1536-height":460,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","2048x2048-width":840,"2048x2048-height":460,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":164,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":219,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e78017f69f6ecf03d3ce4f4633bbcbb8_9cbe9596.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":329}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152689,"id":152689,"title":"5dc63b16aedec5a1735afd953487944d_04371a57.jpg","filename":"5dc63b16aedec5a1735afd953487944d_04371a57.jpg","filesize":67496,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/5dc63b16aedec5a1735afd953487944d_04371a57-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5dc63b16aedec5a1735afd953487944d_04371a57-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:35","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":840,"height":460,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57-300x164.jpg","medium-width":300,"medium-height":164,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57-768x421.jpg","medium_large-width":768,"medium_large-height":421,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","large-width":840,"large-height":460,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","1536x1536-width":840,"1536x1536-height":460,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","2048x2048-width":840,"2048x2048-height":460,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":164,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":219,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc63b16aedec5a1735afd953487944d_04371a57.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":329}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152696,"id":152696,"title":"a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","filename":"a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","filesize":56552,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/a078c48476aa7bec34d1d05e44a5642a_4e655904-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a078c48476aa7bec34d1d05e44a5642a_4e655904-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:36","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":840,"height":460,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904-300x164.jpg","medium-width":300,"medium-height":164,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904-768x421.jpg","medium_large-width":768,"medium_large-height":421,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","large-width":840,"large-height":460,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","1536x1536-width":840,"1536x1536-height":460,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","2048x2048-width":840,"2048x2048-height":460,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":164,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":219,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a078c48476aa7bec34d1d05e44a5642a_4e655904.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":329}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152703,"id":152703,"title":"784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","filename":"784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","filesize":252022,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/784772cf140d66c52a608eb50b92b644_b50a5e01-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"784772cf140d66c52a608eb50b92b644_b50a5e01-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:37","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":960,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","medium_large-width":720,"medium_large-height":960,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","large-width":720,"large-height":960,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","1536x1536-width":720,"1536x1536-height":960,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","2048x2048-width":720,"2048x2048-height":960,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/784772cf140d66c52a608eb50b92b644_b50a5e01.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152710,"id":152710,"title":"e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","filename":"e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","filesize":311189,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:38","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":960,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","medium_large-width":720,"medium_large-height":960,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","large-width":720,"large-height":960,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","1536x1536-width":720,"1536x1536-height":960,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","2048x2048-width":720,"2048x2048-height":960,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e53fcb9c4ae9c1ef4b623b7e2f991e68_9751c0eb.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152717,"id":152717,"title":"da4f3580768f7b0506599a735e872a19_3435be09.jpg","filename":"da4f3580768f7b0506599a735e872a19_3435be09.jpg","filesize":110297,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/da4f3580768f7b0506599a735e872a19_3435be09-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"da4f3580768f7b0506599a735e872a19_3435be09-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:39","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":840,"height":460,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09-300x164.jpg","medium-width":300,"medium-height":164,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09-768x421.jpg","medium_large-width":768,"medium_large-height":421,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","large-width":840,"large-height":460,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","1536x1536-width":840,"1536x1536-height":460,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","2048x2048-width":840,"2048x2048-height":460,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":164,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":219,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/da4f3580768f7b0506599a735e872a19_3435be09.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":329}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152724,"id":152724,"title":"4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","filename":"4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","filesize":16705,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/4bbd63f9854c83a07df6884ca8652e55_04b74466-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4bbd63f9854c83a07df6884ca8652e55_04b74466-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:40","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":445,"height":441,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466-300x297.jpg","medium-width":300,"medium-height":297,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","medium_large-width":445,"medium_large-height":441,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","large-width":445,"large-height":441,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","1536x1536-width":445,"1536x1536-height":441,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","2048x2048-width":445,"2048x2048-height":441,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":297,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":396,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4bbd63f9854c83a07df6884ca8652e55_04b74466.jpg","gform-image-choice-lg-width":445,"gform-image-choice-lg-height":441}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152731,"id":152731,"title":"f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","filename":"f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","filesize":234842,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:41","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1125,"height":844,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","1536x1536-width":1125,"1536x1536-height":844,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","2048x2048-width":1125,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f58ec6fadb5aa4bab1e749ebbfe466c3_efb4455f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152738,"id":152738,"title":"880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","filename":"880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","filesize":181246,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/880f58bef2b73e3c193b35d2d43dedbc_3699153a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"880f58bef2b73e3c193b35d2d43dedbc_3699153a-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:42","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1125,"height":844,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","1536x1536-width":1125,"1536x1536-height":844,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","2048x2048-width":1125,"2048x2048-height":844,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/880f58bef2b73e3c193b35d2d43dedbc_3699153a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152745,"id":152745,"title":"1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","filename":"1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","filesize":154626,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/1f2661f784955a5019bdd1b45310b83c_dbf9b936-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1f2661f784955a5019bdd1b45310b83c_dbf9b936-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:43","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":960,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","1536x1536-width":1440,"1536x1536-height":960,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","2048x2048-width":1440,"2048x2048-height":960,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f2661f784955a5019bdd1b45310b83c_dbf9b936.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152752,"id":152752,"title":"797fc19a0396fdac3634baa9f0a3b955_e384fb96.jpg","filename":"797fc19a0396fdac3634baa9f0a3b955_e384fb96.jpg","filesize":336419,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"797fc19a0396fdac3634baa9f0a3b955_e384fb96-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:44","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":2160,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96-1365x2048.jpg","2048x2048-width":1365,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/797fc19a0396fdac3634baa9f0a3b955_e384fb96.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152759,"id":152759,"title":"bcc91bfdb4528d3e9983605332565fe1_fa1e55ce.jpg","filename":"bcc91bfdb4528d3e9983605332565fe1_fa1e55ce.jpg","filesize":309344,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:46","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":2160,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce-1365x2048.jpg","2048x2048-width":1365,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bcc91bfdb4528d3e9983605332565fe1_fa1e55ce.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152766,"id":152766,"title":"b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","filename":"b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","filesize":315939,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/bb-da-bice\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b3ac31eabc3d12f3099253d96086566d_22bc6ac3-jpg-2","status":"inherit","uploaded_to":182384,"date":"2025-04-17 14:55:48","modified":"2025-04-18 14:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1440,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","2048x2048-width":1440,"2048x2048-height":1920,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3ac31eabc3d12f3099253d96086566d_22bc6ac3.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.705244","longitude":"9.686037","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"24124","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"3397601997","iu_cell":"3397601997","iu_email":"biceperico@hotmail.it","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"8747","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","id_eppen":"","hours":"","accessibilityicons":[],"description":"<p>B&#038;B Da Bice znajduje si\u0119 w malowniczym Borgo Santa Caterina, zaledwie kilka krok\u00f3w od Dolnego Miasta, centrum handlowego Bergamo, i od G\u00f3rnego Miasta, starego miasta. Ugo\u015bcimy Ci\u0119 w jednym z dw\u00f3ch \u0142adnych apartament\u00f3w wyposa\u017conych w podw\u00f3jne \u0142\u00f3\u017cko, prywatn\u0105 \u0142azienk\u0119 i kuchni\u0119 z wszelkimi udogodnieniami, gdzie ka\u017cdego ranka b\u0119dziemy serwowa\u0107 obfite \u015bniadanie oparte na lokalnych produktach. Przez ca\u0142y czas trwania pobytu kuchnia pozostanie do Twojej dyspozycji r\u00f3wnie\u017c na obiady i kolacje.<br \/>\nNiezale\u017cne wej\u015bcie gwarantuje doskona\u0142e poszanowanie Twojej prywatno\u015bci.<\/p>\n<p>Internet Wi-Fi, radio, telewizor i telefon.<br \/>\nMo\u017cliwo\u015b\u0107 dostawienia trzeciego \u0142\u00f3\u017cka bez dodatkowych op\u0142at.<br \/>\nKryty, strze\u017cony parking.<\/p>\n<p>Nasze apartamenty s\u0105 wyposa\u017cone we wszystko: podw\u00f3jne \u0142\u00f3\u017cko, prywatn\u0105 \u0142azienk\u0119 i w pe\u0142ni wyposa\u017con\u0105 kuchni\u0119. Ponadto ka\u017cdy apartament ma osobne wej\u015bcie, co zapewnia swobod\u0119 poruszania si\u0119, tak jakby\u015b by\u0142 w domu. <\/p>\n","hero_title":"B&B Da Bice","hero_text":"<p>Komfortowy pensjonat B&#038;B po\u0142o\u017cony w malowniczym Borgo Santa Caterina<\/p>\n","howtogetthere":"<p>Z dworca kolejowego: przej\u015b\u0107 200 metr\u00f3w w kierunku Citt\u00e0 Alta do Porta Nuova i wsi\u0105\u015b\u0107 do autobusu miejskiego (linia ATB) nr 11 w kierunku Torre Boldone \/ Ranica na 6 przystankach (oko\u0142o 5 minut).<br \/>\nZ lotniska Orio Al Serio: autobusem miejskim (linie ATB) nr 1 w kierunku centrum miasta do dworca kolejowego.<\/p>\n","price":"<p>\u015arednia cena waha si\u0119 od 50 do 100 euro za noc. Zale\u017cy ona od tego, czy pok\u00f3j dwuosobowy jest przeznaczony do pojedynczego wykorzystania oraz od pory roku. <\/p>\n","iu_addr_streetnumber":"Via Fratelli Bronzetti, 1 b","iu_website":"http:\/\/www.dabice.it","url":"","time":"<p>E&#8217; possibile effettuare il check-in dalle ore 11,30 fino alle ore 21.Il check-out il giorno di partenza deve essere effettuato entro le ore 10,30.\u00a0Eventuali variazioni devono essere comunicate in anticipo al momento della prenotazione.<\/p>\n","iu_company_name":"Bice Perico","iu_vat":"CRRCNZ88A71G535R","iu_stars":"","iu_rooms":"2","iu_beds":"6","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","registered_office":"Via Fratelli Bronzetti 1b 24124 Bergamo Bg","service_icons":[{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/152668"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=182384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=182384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=182384"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=182384"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=182384"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=182384"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=182384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}