{"id":182655,"date":"2025-04-18T13:18:26","date_gmt":"2025-04-18T11:18:26","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/ab-residence-antico-borgo\/"},"modified":"2025-04-18T16:58:23","modified_gmt":"2025-04-18T14:58:23","slug":"ab-residence-antico-borgo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/","title":{"rendered":"Ab Residence Antico Borgo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":158049,"template":"","categories":[1608],"tags":[],"aggr":[],"area":[],"kind":[18727],"zona":[],"class_list":["post-182655","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sen","kind-strutturaricettiva-pl"],"acf":{"slides":[{"image":{"ID":158049,"id":158049,"title":"0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","filename":"0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","filesize":357911,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-jpg-2","status":"inherit","uploaded_to":182655,"date":"2025-04-17 15:18:36","modified":"2025-04-18 14:55:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":766,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-300x145.jpg","medium-width":300,"medium-height":145,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-768x372.jpg","medium_large-width":768,"medium_large-height":372,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-1024x496.jpg","large-width":1024,"large-height":496,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c-1536x745.jpg","1536x1536-width":1536,"1536x1536-height":745,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","2048x2048-width":1580,"2048x2048-height":766,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":145,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":194,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0104af6caa3b4b0d7c13eeccea9c2302_58c86d3c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":291}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158056,"id":158056,"title":"2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","filename":"2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","filesize":397412,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-jpg-2","status":"inherit","uploaded_to":182655,"date":"2025-04-17 15:18:37","modified":"2025-04-18 14:55:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":873,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-300x166.jpg","medium-width":300,"medium-height":166,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-768x424.jpg","medium_large-width":768,"medium_large-height":424,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-1024x566.jpg","large-width":1024,"large-height":566,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00-1536x849.jpg","1536x1536-width":1536,"1536x1536-height":849,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","2048x2048-width":1580,"2048x2048-height":873,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":166,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":221,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2834f7daa7f7dd5e04304ef8703b7cc8_074a2b00.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":332}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158063,"id":158063,"title":"d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","filename":"d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","filesize":308806,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-jpg-2","status":"inherit","uploaded_to":182655,"date":"2025-04-17 15:18:38","modified":"2025-04-18 14:55:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":790,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-300x150.jpg","medium-width":300,"medium-height":150,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-768x384.jpg","medium_large-width":768,"medium_large-height":384,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-1024x512.jpg","large-width":1024,"large-height":512,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd-1536x768.jpg","1536x1536-width":1536,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","2048x2048-width":1580,"2048x2048-height":790,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":150,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":200,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d1477cf36bd1d3e6e7457e3d8c8a3be0_14ccf9fd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":300}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158070,"id":158070,"title":"760de2cddf5f923222424a4786a453f1_40cef298.jpg","filename":"760de2cddf5f923222424a4786a453f1_40cef298.jpg","filesize":431068,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/760de2cddf5f923222424a4786a453f1_40cef298-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"760de2cddf5f923222424a4786a453f1_40cef298-jpg-2","status":"inherit","uploaded_to":182655,"date":"2025-04-17 15:18:40","modified":"2025-04-18 14:55:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":850,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298-300x161.jpg","medium-width":300,"medium-height":161,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298-768x413.jpg","medium_large-width":768,"medium_large-height":413,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298-1024x551.jpg","large-width":1024,"large-height":551,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298-1536x826.jpg","1536x1536-width":1536,"1536x1536-height":826,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298.jpg","2048x2048-width":1580,"2048x2048-height":850,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":161,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":215,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/760de2cddf5f923222424a4786a453f1_40cef298.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":323}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158077,"id":158077,"title":"5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","filename":"5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","filesize":270950,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-jpg-2","status":"inherit","uploaded_to":182655,"date":"2025-04-17 15:18:41","modified":"2025-04-18 14:55:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-300x134.jpg","medium-width":300,"medium-height":134,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-768x343.jpg","medium_large-width":768,"medium_large-height":343,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-1024x458.jpg","large-width":1024,"large-height":458,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101-1536x686.jpg","1536x1536-width":1536,"1536x1536-height":686,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","2048x2048-width":1580,"2048x2048-height":706,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":134,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":179,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ac4bdf2aabdec3c6be9bc48b4ce3705_7d973101.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":268}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":158084,"id":158084,"title":"68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","filename":"68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","filesize":235466,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","link":"https:\/\/visit.valueservice.cloud\/pl\/oggetto\/ab-residence-antico-borgo\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-jpg-2","status":"inherit","uploaded_to":182655,"date":"2025-04-17 15:18:42","modified":"2025-04-18 14:55:36","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":776,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-300x147.jpg","medium-width":300,"medium-height":147,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-768x377.jpg","medium_large-width":768,"medium_large-height":377,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-1024x503.jpg","large-width":1024,"large-height":503,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb-1536x754.jpg","1536x1536-width":1536,"1536x1536-height":754,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","2048x2048-width":1580,"2048x2048-height":776,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":147,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":196,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/68f9b3f7b4e148d63bc1d354a797eea1_cb6932cb.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":295}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.697708","longitude":"9.680606","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"+39 035249550","iu_cell":"+39 3358451516","iu_email":"info@abresidence.com","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"4446","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","id_eppen":"","hours":"","accessibilityicons":[],"url":"","description":"<p>Antico Borgo, mieszcz\u0105cy si\u0119 w ca\u0142kowicie odnowionej staro\u017cytnej rezydencji z 1570 roku, oferuje swoim go\u015bciom nowoczesne i dobrze wyposa\u017cone studia i dwupokojowe apartamenty w ciep\u0142ej i przyjaznej atmosferze. Nasze mieszkania s\u0105 idealnym rozwi\u0105zaniem na ka\u017cd\u0105 potrzeb\u0119, czy to na wakacje, czy na studia i podr\u00f3\u017ce s\u0142u\u017cbowe. Wszystkie mieszkania s\u0105 nowocze\u015bnie wyposa\u017cone, ze wszystkimi udogodnieniami hotelu: w pe\u0142ni wyposa\u017cona kuchnia, kolorowy telewizor, bezprzewodowy internet, niezale\u017cna klimatyzacja i ogrzewanie. Po\u0142o\u017cone w \u0142atwo dost\u0119pnym miejscu, aby skorzysta\u0107 ze wszystkich us\u0142ug i udogodnie\u0144, s\u0105 jednocze\u015bnie przyjazne i wygodne jak w\u0142asny dom.  <\/p>\n","hero_title":"Ab Residence Antico Borgo","hero_text":"<p>Obiekt Antico Borgo oferuje mieszkania w odleg\u0142o\u015bci 500 metr\u00f3w od centrum miasta i 1000 metr\u00f3w od pocz\u0105tku dzielnicy Citt\u00e0 Alta.<\/p>\n","indepth":"<p>Historyczna wioska, w kt\u00f3rej si\u0119 znajduje, jest dobrze obs\u0142ugiwana przez wszystko: bary, cukiernie, restauracje, supermarkety, pizzerie, sklepy specjalistyczne, z\u0142otnik\u00f3w, banki, ko\u015bcio\u0142y i wiele innych. W tym samym budynku znajduje si\u0119 restauracja &#8220;Ol Giop\u00ec e la Marg\u00ec&#8221;, kt\u00f3rej bogate i starannie przygotowane menu oferuje wszystkie tradycyjne dania typowej lokalnej kuchni, kt\u00f3rym towarzysz\u0105 doskona\u0142e wina z dolin Bergamo. Kwalifikuje historyczne rezydencje, stare wiejskie domy i mieszkania w kontek\u015bcie miejskim o warto\u015bci historycznej. <\/p>\n","iu_website":"http:\/\/www.abresidence.com","time":"<p>Check in dalle 11 alle 19 &#8211; se ci avvisate vi aspettiamo fino alle 24 Check out prima delle 10<\/p>\n","iu_company_name":"GI.VA. HOTELS snc DI FOGLIENI","iu_vat":"","iu_stars":"3","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","registered_office":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"restaurant","label":"Ristorante"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"electronic_key","label":"Chiave elettronica"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"amex","label":"American Express"},{"value":"diners","label":"Diners Club"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/oggetto\/182655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media\/158049"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/media?parent=182655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/categories?post=182655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/tags?post=182655"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/aggr?post=182655"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/area?post=182655"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/kind?post=182655"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/pl\/wp-json\/wp\/v2\/zona?post=182655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}