{"id":182329,"date":"2025-04-18T13:07:29","date_gmt":"2025-04-18T11:07:29","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/ca-cianfer\/"},"modified":"2025-04-18T16:50:17","modified_gmt":"2025-04-18T14:50:17","slug":"ca-cianfer","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/","title":{"rendered":"C\u00e0 Cianfer"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":150725,"template":"","categories":[1005],"tags":[],"aggr":[],"area":[],"kind":[18728],"zona":[],"class_list":["post-182329","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-1005","kind-strutturaricettiva-ru"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"C\u00e0 Cianfer","hero_text":"<p>\u041c\u044b \u043d\u0430\u0445\u043e\u0434\u0438\u043c\u0441\u044f \u0432 \u0441\u0430\u043c\u043e\u043c \u0441\u0435\u0440\u0434\u0446\u0435 \u0411\u043e\u0440\u0433\u043e \u0421\u0430\u043d\u0442\u0430-\u041a\u0430\u0442\u0435\u0440\u0438\u043d\u0430, \u043e\u0434\u043d\u043e\u0433\u043e \u0438\u0437 \u0441\u0430\u043c\u044b\u0445 \u043a\u0440\u0430\u0441\u0438\u0432\u044b\u0445 \u043f\u043e\u0441\u0435\u043b\u0435\u043d\u0438\u0439 \u0432 \u0418\u0442\u0430\u043b\u0438\u0438. \u0416\u0438\u0432\u043e\u043f\u0438\u0441\u043d\u044b\u0439 \u0438 \u044f\u0440\u043a\u0438\u0439, \u0411\u043e\u0440\u0433\u043e \u0434\u0438 \u0421\u0430\u043d\u0442\u0430-\u041a\u0430\u0442\u0435\u0440\u0438\u043d\u0430 \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 \u0432\u0441\u0435 \u0432\u0438\u0434\u044b \u0443\u0441\u043b\u0443\u0433. \u0412 \u043d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u0438\u0445 \u0448\u0430\u0433\u0430\u0445 \u043e\u0442 \u0410\u043a\u0430\u0434\u0435\u043c\u0438\u0438 \u041a\u0430\u0440\u0440\u0430\u0440\u0430, GAMeC \u0438 \u043a\u0440\u0430\u0441\u0438\u0432\u043e\u0433\u043e \u0412\u0435\u0440\u0445\u043d\u0435\u0433\u043e \u0413\u043e\u0440\u043e\u0434\u0430, \u0438\u0441\u0442\u043e\u0440\u0438\u0447\u0435\u0441\u043a\u043e\u0433\u043e \u0446\u0435\u043d\u0442\u0440\u0430.<\/p>\n","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":"","order_by":false,"order_way":false}},"description":"<p>C\u00e0 Cianfer \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 \u0442\u0440\u0438 \u0430\u043f\u0430\u0440\u0442\u0430\u043c\u0435\u043d\u0442\u0430: Lo Scoiattolo (\u0411\u0435\u043b\u043a\u0430), La Coccinella (\u0411\u043e\u0436\u044c\u044f \u043a\u043e\u0440\u043e\u0432\u043a\u0430) \u0438 Il Riccio (\u0415\u0436).&#13;<br \/>\n\u0412\u044b\u0431\u043e\u0440 \u044d\u0442\u0438\u0445 \u043d\u0430\u0437\u0432\u0430\u043d\u0438\u0439 \u0432\u0434\u043e\u0445\u043d\u043e\u0432\u043b\u0435\u043d \u043f\u0440\u0438\u043a\u043b\u044e\u0447\u0435\u043d\u0438\u044f\u043c\u0438 \u043d\u0430\u0448\u0435\u0439 \u0441\u0435\u043c\u044c\u0438.&#13;<br \/>\n\u0412\u0441\u0435 \u0430\u043f\u0430\u0440\u0442\u0430\u043c\u0435\u043d\u0442\u044b \u043e\u0441\u043d\u0430\u0449\u0435\u043d\u044b 32-\u0434\u044e\u0439\u043c\u043e\u0432\u044b\u043c HD-\u0441\u043c\u0430\u0440\u0442-LED-\u0442\u0435\u043b\u0435\u0432\u0438\u0437\u043e\u0440\u043e\u043c \u0441 \u043f\u043e\u0434\u043f\u0438\u0441\u043a\u043e\u0439 \u043d\u0430 Prime Video, \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u043c Wi-Fi \u043f\u043e \u0444\u0438\u0431\u0440\u0435, \u0444\u0435\u043d\u043e\u043c, \u043e\u0442\u043e\u043f\u043b\u0435\u043d\u0438\u0435\u043c, \u043a\u043e\u043d\u0434\u0438\u0446\u0438\u043e\u043d\u0435\u0440\u043e\u043c \u0438 USB- \u0438 Micro USB-\u0440\u0430\u0437\u044a\u0435\u043c\u0430\u043c\u0438.&#13;<br \/>\n\u041a\u0443\u0445\u043d\u0438 \u043f\u043e\u043b\u043d\u043e\u0441\u0442\u044c\u044e \u043e\u0431\u043e\u0440\u0443\u0434\u043e\u0432\u0430\u043d\u044b \u0445\u043e\u043b\u043e\u0434\u0438\u043b\u044c\u043d\u0438\u043a\u043e\u043c, \u043c\u043e\u0440\u043e\u0437\u0438\u043b\u044c\u043d\u043e\u0439 \u043a\u0430\u043c\u0435\u0440\u043e\u0439, \u043c\u0438\u043a\u0440\u043e\u0432\u043e\u043b\u043d\u043e\u0432\u043e\u0439 \u043f\u0435\u0447\u044c\u044e, \u0438\u043d\u0434\u0443\u043a\u0446\u0438\u043e\u043d\u043d\u043e\u0439 \u043f\u043b\u0438\u0442\u043e\u0439, \u0447\u0430\u0439\u043d\u0438\u043a\u043e\u043c, \u043a\u043e\u0444\u0435\u0439\u043d\u0438\u043a\u043e\u043c \u043c\u043e\u043a\u043a\u0430, \u043d\u0430\u0431\u043e\u0440\u043e\u043c \u043a\u0430\u0441\u0442\u0440\u044e\u043b\u044c \u0438 \u0432\u0441\u0435\u043c\u0438 \u0430\u043a\u0441\u0435\u0441\u0441\u0443\u0430\u0440\u0430\u043c\u0438 \u0434\u043b\u044f \u043f\u0440\u0438\u0433\u043e\u0442\u043e\u0432\u043b\u0435\u043d\u0438\u044f \u043f\u0438\u0449\u0438.&#13;<br \/>\n\u0412 \u0448\u043a\u0430\u0444\u0430\u0445 \u0441\u043e\u0434\u0435\u0440\u0436\u0430\u0442\u0441\u044f \u0438\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442\u044b \u0438 \u0441\u0440\u0435\u0434\u0441\u0442\u0432\u0430 \u0434\u043b\u044f \u0443\u0431\u043e\u0440\u043a\u0438 \u0430\u043f\u0430\u0440\u0442\u0430\u043c\u0435\u043d\u0442\u043e\u0432.&#13;<br \/>\n\u0412 \u043f\u0440\u0438\u0432\u0435\u0442\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u043c \u044f\u0449\u0438\u043a\u0435 \u0432\u044b \u043d\u0430\u0439\u0434\u0435\u0442\u0435 \u0432\u0441\u0435 \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u043e\u0435 \u043d\u0430 \u043f\u0435\u0440\u0432\u044b\u0435 \u0434\u043d\u0438 \u0438 \u043d\u0435\u0431\u043e\u043b\u044c\u0448\u043e\u0439 \u0441\u0443\u0432\u0435\u043d\u0438\u0440.&#13;<br \/>\n\u0412\u0445\u043e\u0434\u043d\u0430\u044f \u0437\u043e\u043d\u0430, \u043e\u0431\u0449\u0430\u044f \u0434\u043b\u044f \u0442\u0440\u0435\u0445 \u0430\u043f\u0430\u0440\u0442\u0430\u043c\u0435\u043d\u0442\u043e\u0432, \u043f\u043e\u043b\u043d\u043e\u0441\u0442\u044c\u044e \u043a \u0432\u0430\u0448\u0438\u043c \u0443\u0441\u043b\u0443\u0433\u0430\u043c \u0438 \u0441\u043e\u0441\u0442\u043e\u0438\u0442 \u0438\u0437 \u043a\u043d\u0438\u0436\u043d\u043e\u0439 \u043f\u043e\u043b\u043a\u0438, \u0433\u0434\u0435 \u0432\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u043d\u0430\u0439\u0442\u0438 \u043a\u043d\u0438\u0433\u0438 \u043d\u0430 \u043b\u044e\u0431\u043e\u0439 \u0432\u043a\u0443\u0441, \u043d\u0430\u0441\u0442\u043e\u043b\u044c\u043d\u044b\u0435 \u0438\u0433\u0440\u044b \u0434\u043b\u044f \u0432\u0437\u0440\u043e\u0441\u043b\u044b\u0445 \u0438 \u0434\u0435\u0442\u0435\u0439, \u0438 \u0438\u0433\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u043a\u0430\u0440\u0442\u044b.&#13;<br \/>\n\u041a\u0440\u043e\u043c\u0435 \u0442\u043e\u0433\u043e, \u0432\u044b \u043d\u0430\u0439\u0434\u0435\u0442\u0435 \u043d\u0435\u0431\u043e\u043b\u044c\u0448\u043e\u0439 \u0431\u0430\u0440 \u0441 \u043a\u043e\u0444\u0435\u043c\u0430\u0448\u0438\u043d\u043e\u0439 Nespresso \u0438 \u0432\u043e\u0434\u043e\u043d\u0430\u043f\u043e\u0440\u043d\u044b\u043c \u0443\u0441\u0442\u0440\u043e\u0439\u0441\u0442\u0432\u043e\u043c \u0434\u043b\u044f \u0437\u0430\u043f\u043e\u043b\u043d\u0435\u043d\u0438\u044f \u0432\u0430\u0448\u0438\u0445 \u0431\u0443\u0442\u044b\u043b\u043e\u043a (\u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u043e\u0439, \u043a\u043e\u043c\u043d\u0430\u0442\u043d\u043e\u0439, \u0445\u043e\u043b\u043e\u0434\u043d\u043e\u0439 \u0438 \u0433\u0430\u0437\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u043e\u0439).<\/p>\n","indepth":"<p>\u0421 2019 \u0433\u043e\u0434\u0430 \u0411\u043e\u0440\u0433\u043e \u0421\u0430\u043d\u0442\u0430-\u041a\u0430\u0442\u0435\u0440\u0438\u043d\u0430 \u0441\u0442\u0430\u043b \u0447\u0430\u0441\u0442\u044c\u044e \u0421\u0430\u043c\u044b\u0445 \u041a\u0440\u0430\u0441\u0438\u0432\u044b\u0445 \u0414\u0435\u0440\u0435\u0432\u0435\u043d\u044c \u0418\u0442\u0430\u043b\u0438\u0438.&#13;<br \/>\n\u0422\u0430\u043a\u0436\u0435 \u0438\u0437\u0432\u0435\u0441\u0442\u043d\u044b\u0439 \u043a\u0430\u043a \u0411\u043e\u0440\u0433\u043e \u0434&#8217;\u041e\u0440\u043e, \u044d\u0442\u043e \u043d\u0435\u0431\u043e\u043b\u044c\u0448\u043e\u0435 \u0441\u043e\u043a\u0440\u043e\u0432\u0438\u0449\u0435 \u0447\u0443\u0434\u0435\u0441, \u043e\u043a\u0440\u0443\u0436\u0435\u043d\u043d\u043e\u0435 \u0443\u043d\u0438\u043a\u0430\u043b\u044c\u043d\u043e\u0439 \u0430\u0442\u043c\u043e\u0441\u0444\u0435\u0440\u043e\u0439, \u0441\u043e\u0441\u0442\u043e\u044f\u0449\u0435\u0439 \u0438\u0437 \u0441\u0442\u0430\u0440\u0438\u043d\u043d\u044b\u0445 \u0437\u0434\u0430\u043d\u0438\u0439, \u044f\u0440\u043a\u0438\u0445 \u0432\u0438\u0442\u0440\u0438\u043d \u0438 \u0437\u0430\u043c\u0430\u043d\u0447\u0438\u0432\u043e\u0439 \u0433\u0430\u0441\u0442\u0440\u043e\u043d\u043e\u043c\u0438\u0438.<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"<p>\u0411\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u043e \u0434\u043e \u0438\u0441\u0447\u0435\u0440\u043f\u0430\u043d\u0438\u044f \u043c\u0435\u0441\u0442 \u0432\u043e \u0432\u043d\u0443\u0442\u0440\u0435\u043d\u043d\u0435\u043c \u0434\u0432\u043e\u0440\u0435. \u041d\u0430 \u0441\u043e\u0441\u0435\u0434\u043d\u0438\u0445 \u0443\u043b\u0438\u0446\u0430\u0445 \u043c\u043e\u0436\u043d\u043e \u043d\u0430\u0439\u0442\u0438 \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u0435 \u043f\u0430\u0440\u043a\u043e\u0432\u043e\u0447\u043d\u044b\u0435 \u043c\u0435\u0441\u0442\u0430 (\u0431\u0435\u043b\u044b\u0435 \u043f\u043e\u043b\u043e\u0441\u044b) \u0438\u043b\u0438 \u043f\u043b\u0430\u0442\u043d\u044b\u0435 (\u0441\u0438\u043d\u0438\u0435 \u043f\u043e\u043b\u043e\u0441\u044b).<\/p>\n","restaurant":"<p>\u0412 \u043e\u043a\u0440\u0435\u0441\u0442\u043d\u043e\u0441\u0442\u044f\u0445 \u043c\u043d\u043e\u0433\u043e \u0440\u0435\u0441\u0442\u043e\u0440\u0430\u043d\u043e\u0432<\/p>\n","breakfast":"<p>\u0412\u043e\u0437\u043c\u043e\u0436\u043d\u043e\u0441\u0442\u044c \u0437\u0430\u0432\u0442\u0440\u0430\u043a\u0430 \u0432 \u043d\u043e\u043c\u0435\u0440\u0435 \u0447\u0435\u0440\u0435\u0437 \u0443\u0441\u043b\u0443\u0433\u0443 \u0434\u043e\u0441\u0442\u0430\u0432\u043a\u0438, \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u043c\u0443\u044e \u0431\u0430\u0440\u0430\u043c\u0438 \u0432 \u0434\u0435\u0440\u0435\u0432\u043d\u0435.<\/p>\n","internet":"<p>\u0411\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u0439 Wi-Fi \u043f\u043e \u043e\u043f\u0442\u043e\u0432\u043e\u043b\u043e\u043a\u043e\u043d\u043d\u043e\u0439 \u0441\u0435\u0442\u0438<\/p>\n","children":"<p>\u041f\u043e\u0434\u0445\u043e\u0434\u0438\u0442 \u0434\u043b\u044f \u0441\u0435\u043c\u0435\u0439\u043d\u043e\u0433\u043e \u043e\u0442\u0434\u044b\u0445\u0430<\/p>\n","pets":"<p>\u041d\u0435 \u0440\u0430\u0437\u0440\u0435\u0448\u0435\u043d<\/p>\n","latitude":"45.705023","longitude":"9.683530","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"C\u00e0 Cianfer di Silvia Cambianica","registered_office":"Via Longo,8 Bergamo 24124","iu_addr_streetnumber":"Via Guglielmo Longo, 8","iu_addr_postalcode":"24124","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"3286077207","iu_cell":"3286077207","iu_website":"http:\/\/www.cacianfer.it","iu_email":"info@cacianfer.it","iu_vat":"04490560168","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"10776","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"slides":[{"image":{"ID":150725,"id":150725,"title":"fee13191e4aa0ea2c87c6e1d0562ef09_9825d589.jpg","filename":"fee13191e4aa0ea2c87c6e1d0562ef09_9825d589.jpg","filesize":878428,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:38","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1690,"height":2291,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-221x300.jpg","medium-width":221,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-768x1041.jpg","medium_large-width":768,"medium_large-height":1041,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-755x1024.jpg","large-width":755,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-1133x1536.jpg","1536x1536-width":1133,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589-1511x2048.jpg","2048x2048-width":1511,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589.jpg","gform-image-choice-sm-width":221,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589.jpg","gform-image-choice-md-width":295,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fee13191e4aa0ea2c87c6e1d0562ef09_9825d589.jpg","gform-image-choice-lg-width":443,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150732,"id":150732,"title":"34a9bf94a639d30099858928b8debb8e_24cbd882.jpg","filename":"34a9bf94a639d30099858928b8debb8e_24cbd882.jpg","filesize":1169918,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/34a9bf94a639d30099858928b8debb8e_24cbd882-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"34a9bf94a639d30099858928b8debb8e_24cbd882-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:40","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2160,"height":1645,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882-300x228.jpg","medium-width":300,"medium-height":228,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882-768x585.jpg","medium_large-width":768,"medium_large-height":585,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882-1024x780.jpg","large-width":1024,"large-height":780,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882-1536x1170.jpg","1536x1536-width":1536,"1536x1536-height":1170,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882-2048x1560.jpg","2048x2048-width":2048,"2048x2048-height":1560,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":228,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":305,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/34a9bf94a639d30099858928b8debb8e_24cbd882.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":457}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150739,"id":150739,"title":"efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","filename":"efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","filesize":290614,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/efbb66e71207e15265106e82f9710c57_3c9121c8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"efbb66e71207e15265106e82f9710c57_3c9121c8-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:41","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1067,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","2048x2048-width":1600,"2048x2048-height":1067,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/efbb66e71207e15265106e82f9710c57_3c9121c8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150746,"id":150746,"title":"ae0d51fa48c346819444e71d0e220386_58375920.jpg","filename":"ae0d51fa48c346819444e71d0e220386_58375920.jpg","filesize":269198,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/ae0d51fa48c346819444e71d0e220386_58375920-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ae0d51fa48c346819444e71d0e220386_58375920-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:42","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1067,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920.jpg","2048x2048-width":1067,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ae0d51fa48c346819444e71d0e220386_58375920.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150753,"id":150753,"title":"3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","filename":"3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","filesize":211651,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:44","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1067,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","2048x2048-width":1067,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9475fbe6d0ba65e9415e47c6e3ba9e_5ccb0afb.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150760,"id":150760,"title":"a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","filename":"a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","filesize":165108,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a23ba1b874ab8ac73555c483e505637c_b12ab5cd-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:45","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1067,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","2048x2048-width":1067,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a23ba1b874ab8ac73555c483e505637c_b12ab5cd.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150767,"id":150767,"title":"58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","filename":"58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","filesize":215003,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:46","modified":"2025-04-18 14:50:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1067,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","2048x2048-width":1600,"2048x2048-height":1067,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58b7c3b5db9db0d227fe507be50e91c6_d3cd253e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150774,"id":150774,"title":"a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","filename":"a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","filesize":177880,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:47","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":949,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-178x300.jpg","medium-width":178,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-768x1295.jpg","medium_large-width":768,"medium_large-height":1295,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-607x1024.jpg","large-width":607,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b-911x1536.jpg","1536x1536-width":911,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","2048x2048-width":949,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","gform-image-choice-sm-width":178,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","gform-image-choice-md-width":237,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a0fcfc5b2388231ca2ad8e56074759bc_4f52139b.jpg","gform-image-choice-lg-width":356,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150781,"id":150781,"title":"c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","filename":"c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","filesize":185532,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/c636a3ca5500c8bf29084620a0d061a1_b483036e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c636a3ca5500c8bf29084620a0d061a1_b483036e-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:48","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":888,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e-167x300.jpg","medium-width":167,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e-768x1384.jpg","medium_large-width":768,"medium_large-height":1384,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e-568x1024.jpg","large-width":568,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e-852x1536.jpg","1536x1536-width":852,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","2048x2048-width":888,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","gform-image-choice-sm-width":167,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","gform-image-choice-md-width":222,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c636a3ca5500c8bf29084620a0d061a1_b483036e.jpg","gform-image-choice-lg-width":333,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150788,"id":150788,"title":"3cf830918769f980136a20b6086fcbed_8d946029.jpg","filename":"3cf830918769f980136a20b6086fcbed_8d946029.jpg","filesize":182237,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/3cf830918769f980136a20b6086fcbed_8d946029-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3cf830918769f980136a20b6086fcbed_8d946029-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:49","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":872,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029-164x300.jpg","medium-width":164,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029-768x1409.jpg","medium_large-width":768,"medium_large-height":1409,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029-558x1024.jpg","large-width":558,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029-837x1536.jpg","1536x1536-width":837,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029.jpg","2048x2048-width":872,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029.jpg","gform-image-choice-sm-width":164,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029.jpg","gform-image-choice-md-width":218,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3cf830918769f980136a20b6086fcbed_8d946029.jpg","gform-image-choice-lg-width":327,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150795,"id":150795,"title":"48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","filename":"48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","filesize":169855,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:51","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1284,"height":846,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e-768x506.jpg","medium_large-width":768,"medium_large-height":506,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e-1024x675.jpg","large-width":1024,"large-height":675,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","1536x1536-width":1284,"1536x1536-height":846,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","2048x2048-width":1284,"2048x2048-height":846,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":264,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48ff03a0fd8ea5f7d3b4a267f20a08f9_d462056e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":395}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150802,"id":150802,"title":"eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","filename":"eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","filesize":159722,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:52","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":929,"height":1382,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d-202x300.jpg","medium-width":202,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d-768x1142.jpg","medium_large-width":768,"medium_large-height":1142,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d-688x1024.jpg","large-width":688,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","1536x1536-width":929,"1536x1536-height":1382,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","2048x2048-width":929,"2048x2048-height":1382,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","gform-image-choice-sm-width":202,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","gform-image-choice-md-width":269,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eb853a3e02e5de401f1c4acc58d72bb0_13d65b1d.jpg","gform-image-choice-lg-width":403,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150809,"id":150809,"title":"23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","filename":"23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","filesize":103351,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/23776da65f23a7f8fc9b0151e637463b_fe103a5f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"23776da65f23a7f8fc9b0151e637463b_fe103a5f-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:53","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":642,"height":957,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f-201x300.jpg","medium-width":201,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","medium_large-width":642,"medium_large-height":957,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","large-width":642,"large-height":957,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","1536x1536-width":642,"1536x1536-height":957,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","2048x2048-width":642,"2048x2048-height":957,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","gform-image-choice-sm-width":201,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","gform-image-choice-md-width":268,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23776da65f23a7f8fc9b0151e637463b_fe103a5f.jpg","gform-image-choice-lg-width":403,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":150816,"id":150816,"title":"09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","filename":"09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","filesize":116390,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/ca-cianfer\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-jpg-2","status":"inherit","uploaded_to":182329,"date":"2025-04-17 14:47:53","modified":"2025-04-18 14:50:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1066,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-768x1153.jpg","medium_large-width":768,"medium_large-height":1153,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-682x1024.jpg","large-width":682,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601-1023x1536.jpg","1536x1536-width":1023,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","2048x2048-width":1066,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/09d4c76d0bd1e5b1018d6fd48778f7fc_d36e7601.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"time":"<p>Check-in dalle 14.00 alle 23.00&#13;<br \/>\nCheck-out entro le ore 11.00&#13;<br \/>\nSi accettano arrivi oltre le ore 23.00 previo appuntamento orario.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"electronic_key","label":"Chiave elettronica"},{"value":"mini_bar","label":"Frigo bar"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"},{"value":"diners","label":"Diners Club"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto\/182329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto\/182329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/media\/150725"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/media?parent=182329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/categories?post=182329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/tags?post=182329"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/aggr?post=182329"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/area?post=182329"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/kind?post=182329"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/zona?post=182329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}