{"id":182949,"date":"2025-04-18T13:22:07","date_gmt":"2025-04-18T11:22:07","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/starhotels-cristallo-palace\/"},"modified":"2025-04-18T17:03:04","modified_gmt":"2025-04-18T15:03:04","slug":"starhotels-cristallo-palace","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/","title":{"rendered":"Starhotels Cristallo Palace"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":161291,"template":"","categories":[1005],"tags":[],"aggr":[],"area":[],"kind":[18728],"zona":[],"class_list":["post-182949","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-1005","kind-strutturaricettiva-ru"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Starhotels Cristallo Palace","hero_text":"<p><span style='color: #000000;'>\u041e\u0442\u0435\u043b\u044c \u0440\u0430\u0441\u043f\u043e\u043b\u043e\u0436\u0435\u043d \u043d\u0435\u0434\u0430\u043b\u0435\u043a\u043e \u043e\u0442 \u0430\u044d\u0440\u043e\u043f\u043e\u0440\u0442\u0430 \u0438 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u043e\u0433\u043e \u0432\u043e\u043a\u0437\u0430\u043b\u0430 \u0438 \u0432 \u043d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u0438\u0445 \u043c\u0438\u043d\u0443\u0442\u0430\u0445 \u0445\u043e\u0434\u044c\u0431\u044b \u043e\u0442 \u0441\u0440\u0435\u0434\u043d\u0435\u0432\u0435\u043a\u043e\u0432\u044b\u0445 \u0443\u043b\u043e\u0447\u0435\u043a \u0412\u0435\u0440\u0445\u043d\u0435\u0433\u043e \u0433\u043e\u0440\u043e\u0434\u0430 \u0411\u0435\u0440\u0433\u0430\u043c\u043e.<\/span><\/p>\n","slides":[{"image":{"ID":161291,"id":161291,"title":"9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8.jpg","filename":"9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-scaled.jpg","filesize":469203,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:21","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1698,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-768x509.jpg","medium_large-width":768,"medium_large-height":509,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-1024x679.jpg","large-width":1024,"large-height":679,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-1536x1019.jpg","1536x1536-width":1536,"1536x1536-height":1019,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-2048x1358.jpg","2048x2048-width":2048,"2048x2048-height":1358,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":265,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9977bfa6cc144f9ac1e7f04a719d120f_f2888cb8-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161298,"id":161298,"title":"2e111db94074c8b557a6b668755f1609_b522c8ce.jpg","filename":"2e111db94074c8b557a6b668755f1609_b522c8ce-scaled.jpg","filesize":796116,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/2e111db94074c8b557a6b668755f1609_b522c8ce-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2e111db94074c8b557a6b668755f1609_b522c8ce-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:24","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1714,"height":2560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-201x300.jpg","medium-width":201,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-768x1147.jpg","medium_large-width":768,"medium_large-height":1147,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-685x1024.jpg","large-width":685,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-1028x1536.jpg","1536x1536-width":1028,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-1371x2048.jpg","2048x2048-width":1371,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-scaled.jpg","gform-image-choice-sm-width":201,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-scaled.jpg","gform-image-choice-md-width":268,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2e111db94074c8b557a6b668755f1609_b522c8ce-scaled.jpg","gform-image-choice-lg-width":402,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161305,"id":161305,"title":"457328f1e99e8955632c9b827a359cf8_7948ff5b.jpg","filename":"457328f1e99e8955632c9b827a359cf8_7948ff5b-scaled.jpg","filesize":603155,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/457328f1e99e8955632c9b827a359cf8_7948ff5b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"457328f1e99e8955632c9b827a359cf8_7948ff5b-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:26","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/457328f1e99e8955632c9b827a359cf8_7948ff5b-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161312,"id":161312,"title":"5dc805cadec11fe7a9259e005be1dfee_a841f4de.jpg","filename":"5dc805cadec11fe7a9259e005be1dfee_a841f4de-scaled.jpg","filesize":358045,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5dc805cadec11fe7a9259e005be1dfee_a841f4de-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:30","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dc805cadec11fe7a9259e005be1dfee_a841f4de-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161319,"id":161319,"title":"de1beb3b132d837846d6a3eea5ba67f5_addccc70.jpg","filename":"de1beb3b132d837846d6a3eea5ba67f5_addccc70-scaled.jpg","filesize":712475,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"de1beb3b132d837846d6a3eea5ba67f5_addccc70-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:33","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1714,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-2048x1371.jpg","2048x2048-width":2048,"2048x2048-height":1371,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/de1beb3b132d837846d6a3eea5ba67f5_addccc70-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161326,"id":161326,"title":"59a39bc2153cef454c8f385b52b83af2_12b55ffd.jpg","filename":"59a39bc2153cef454c8f385b52b83af2_12b55ffd-scaled.jpg","filesize":817519,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"59a39bc2153cef454c8f385b52b83af2_12b55ffd-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:35","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1714,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-2048x1371.jpg","2048x2048-width":2048,"2048x2048-height":1371,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/59a39bc2153cef454c8f385b52b83af2_12b55ffd-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161333,"id":161333,"title":"4937260f298d057e529b1e838ada9017_dcd33ac4.jpg","filename":"4937260f298d057e529b1e838ada9017_dcd33ac4-scaled.jpg","filesize":484141,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/4937260f298d057e529b1e838ada9017_dcd33ac4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4937260f298d057e529b1e838ada9017_dcd33ac4-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:38","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4937260f298d057e529b1e838ada9017_dcd33ac4-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161340,"id":161340,"title":"30c436f395d4598ffaabae15513fd4eb_f68a8314.jpg","filename":"30c436f395d4598ffaabae15513fd4eb_f68a8314-scaled.jpg","filesize":540612,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/30c436f395d4598ffaabae15513fd4eb_f68a8314-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"30c436f395d4598ffaabae15513fd4eb_f68a8314-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:40","modified":"2025-04-18 15:03:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/30c436f395d4598ffaabae15513fd4eb_f68a8314-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161347,"id":161347,"title":"abf61f5725bc398a62e03039c905f48f_858252cc.jpg","filename":"abf61f5725bc398a62e03039c905f48f_858252cc-scaled.jpg","filesize":406304,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/abf61f5725bc398a62e03039c905f48f_858252cc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"abf61f5725bc398a62e03039c905f48f_858252cc-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:43","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/abf61f5725bc398a62e03039c905f48f_858252cc-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161354,"id":161354,"title":"ff982251054bedce95e15fadb6d492db_adeb503f.jpg","filename":"ff982251054bedce95e15fadb6d492db_adeb503f-scaled.jpg","filesize":349733,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/ff982251054bedce95e15fadb6d492db_adeb503f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ff982251054bedce95e15fadb6d492db_adeb503f-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:46","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ff982251054bedce95e15fadb6d492db_adeb503f-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161361,"id":161361,"title":"5b45a34948991a3662734c1d88d795a3_ad995cb7.jpg","filename":"5b45a34948991a3662734c1d88d795a3_ad995cb7-scaled.jpg","filesize":338707,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/5b45a34948991a3662734c1d88d795a3_ad995cb7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5b45a34948991a3662734c1d88d795a3_ad995cb7-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:50","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5b45a34948991a3662734c1d88d795a3_ad995cb7-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161368,"id":161368,"title":"fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab.jpg","filename":"fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-scaled.jpg","filesize":391703,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:53","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fc4ec2bfb3f6618fb21895b48d3eb147_95a416ab-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161375,"id":161375,"title":"b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","filename":"b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","filesize":394514,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/b216f359d56a32d317d762cc8fea349e_36c9b301-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b216f359d56a32d317d762cc8fea349e_36c9b301-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:55","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1440,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","2048x2048-width":1920,"2048x2048-height":1440,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b216f359d56a32d317d762cc8fea349e_36c9b301.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161382,"id":161382,"title":"0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","filename":"0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","filesize":386819,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0db34f731d1bca64bd3a0a1865ea2428_d2390d97-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:57","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1285,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","2048x2048-width":1920,"2048x2048-height":1285,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0db34f731d1bca64bd3a0a1865ea2428_d2390d97.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":161389,"id":161389,"title":"9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","filename":"9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","filesize":380411,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/starhotels-cristallo-palace\/9c4884a4a765776d7bff3d12f38150df_c7617d9a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9c4884a4a765776d7bff3d12f38150df_c7617d9a-jpg-2","status":"inherit","uploaded_to":182949,"date":"2025-04-18 08:32:58","modified":"2025-04-18 15:03:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":900,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a-300x141.jpg","medium-width":300,"medium-height":141,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a-768x360.jpg","medium_large-width":768,"medium_large-height":360,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a-1024x480.jpg","large-width":1024,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a-1536x720.jpg","1536x1536-width":1536,"1536x1536-height":720,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","2048x2048-width":1920,"2048x2048-height":900,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":141,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":188,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9c4884a4a765776d7bff3d12f38150df_c7617d9a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":281}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"<p>\u0412 \u043d\u0435\u0441\u043a\u043e\u043b\u044c\u043a\u0438\u0445 \u043c\u0438\u043d\u0443\u0442\u0430\u0445 \u0435\u0437\u0434\u044b \u043e\u0442 \u0430\u044d\u0440\u043e\u043f\u043e\u0440\u0442\u0430, \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u043e\u0433\u043e \u0432\u043e\u043a\u0437\u0430\u043b\u0430 \u0438 \u0446\u0435\u043d\u0442\u0440\u0430 \u0433\u043e\u0440\u043e\u0434\u0430, Cristallo Palace \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 \u0432\u0441\u0435 \u0443\u0434\u043e\u0431\u0441\u0442\u0432\u0430 4-\u0437\u0432\u0435\u0437\u0434\u043e\u0447\u043d\u043e\u0433\u043e \u043e\u0442\u0435\u043b\u044f, \u0432 \u0442\u043e\u043c \u0447\u0438\u0441\u043b\u0435 \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u0443\u044e \u043e\u0442\u043a\u0440\u044b\u0442\u0443\u044e \u043f\u0430\u0440\u043a\u043e\u0432\u043a\u0430, \u0433\u0430\u0440\u0430\u0436, \u043f\u0440\u043e\u043a\u0430\u0442 \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u0435\u0439 (SIXT). \u041e\u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u0435\u0441\u044c \u0432 \u044d\u043a\u0441\u043a\u043b\u044e\u0437\u0438\u0432\u043d\u043e\u043c \u043e\u0442\u0435\u043b\u0435, \u043a\u043e\u0442\u043e\u0440\u044b\u0439, \u043a\u0430\u0436\u0435\u0442\u0441\u044f, \u043f\u043e\u0441\u0442\u0440\u043e\u0435\u043d \u043f\u043e\u043b\u043d\u043e\u0441\u0442\u044c\u044e \u0438\u0437 \u0445\u0440\u0443\u0441\u0442\u0430\u043b\u044f. \u0412 \u043e\u0442\u0435\u043b\u0435 \u0435\u0441\u0442\u044c \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u0439 \u0442\u0440\u0430\u043d\u0441\u0444\u0435\u0440 \u0434\u043e \u0446\u0435\u043d\u0442\u0440\u0430 \u0433\u043e\u0440\u043e\u0434\u0430 \u0438 \u0434\u043e \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u043e\u0433\u043e \u0432\u043e\u043a\u0437\u0430\u043b\u0430 (\u0441 \u043f\u043e\u043d\u0435\u0434\u0435\u043b\u044c\u043d\u0438\u043a\u0430 \u043f\u043e \u043f\u044f\u0442\u043d\u0438\u0446\u0443). \u0417\u0430\u0432\u0435\u0440\u0448\u0430\u044e\u0442 \u043f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u0438\u0435 7 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446-\u0437\u0430\u043b\u043e\u0432 \u0434\u043b\u044f \u043f\u0440\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u044f \u0441\u043e\u0432\u0435\u0449\u0430\u043d\u0438\u0439 \u0438 \u0431\u0438\u0437\u043d\u0435\u0441-\u0443\u0441\u043b\u0443\u0433\u0438 \u0434\u043b\u044f \u0440\u0430\u0437\u043c\u0435\u0449\u0435\u043d\u0438\u044f \u0434\u043e 450 \u0447\u0435\u043b\u043e\u0432\u0435\u043a, \u0443\u0441\u043b\u0443\u0433\u0438 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0433\u043e \u043f\u0438\u0442\u0430\u043d\u0438\u044f \u0440\u0435\u0441\u0442\u043e\u0440\u0430\u043d\u0430 Antica Perosa \u0438 Perry\u2019s American Bar, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u0440\u0430\u0431\u043e\u0442\u0430\u044e\u0442 \u0435\u0436\u0435\u0434\u043d\u0435\u0432\u043d\u043e.\u00a0<\/p>\n","indepth":"<p>\u0422\u0440\u0430\u043d\u0441\u0444\u0435\u0440 \u0434\u043e \u0430\u044d\u0440\u043e\u043f\u043e\u0440\u0442\u0430 \u041e\u0440\u0438\u043e-\u0430\u043b\u044c-\u0421\u0435\u0440\u0438\u043e: \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u0437\u0430 \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u0443\u044e \u043f\u043b\u0430\u0442\u0443 \u0438 \u043f\u043e \u0437\u0430\u043f\u0440\u043e\u0441\u0443 (\u043d\u0430\u0447\u0438\u043d\u0430\u044f \u0441 4 \u0435\u0432\u0440\u043e \u043d\u0430 \u0447\u0435\u043b\u043e\u0432\u0435\u043a\u0430)<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"<p>\u041c\u044b \u0441 \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u0435\u043c \u0440\u0430\u0437\u043c\u0435\u0441\u0442\u0438\u043c \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u043c\u0430\u043b\u0435\u043d\u044c\u043a\u043e\u0433\u043e \u0438 \u0441\u0440\u0435\u0434\u043d\u0435\u0433\u043e \u0440\u0430\u0437\u043c\u0435\u0440\u0430. \u041e\u0431 \u0438\u0445 \u043f\u0440\u043e\u0436\u0438\u0432\u0430\u043d\u0438\u0438 \u043e\u0442\u0435\u043b\u044c \u0434\u043e\u043b\u0436\u0435\u043d \u0431\u044b\u0442\u044c \u0443\u0432\u0435\u0434\u043e\u043c\u043b\u0435\u043d \u0432 \u043c\u043e\u043c\u0435\u043d\u0442 \u0431\u0440\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f. \u041c\u043e\u0436\u0435\u0442 \u043f\u043e\u0442\u0440\u0435\u0431\u043e\u0432\u0430\u0442\u044c\u0441\u044f \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u0430\u044f \u043f\u043b\u0430\u0442\u0430. \u0414\u043b\u044f \u043f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u044f \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0439 \u0438\u043d\u0444\u043e\u0440\u043c\u0430\u0446\u0438\u0438 \u043f\u043e\u0436\u0430\u043b\u0443\u0439\u0441\u0442\u0430 \u0441\u0432\u044f\u0436\u0438\u0442\u0435\u0441\u044c \u043d\u0435\u043f\u043e\u0441\u0440\u0435\u0434\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u0441 \u043e\u0442\u0435\u043b\u0435\u043c.&#13;<br \/>\n\u043e\u0442\u0435\u043b\u044c \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u0435\u0442 7 \u0441\u043e\u0432\u0440\u0435\u043c\u0435\u043d\u043d\u044b\u0445 \u043a\u043e\u043d\u0444\u0435\u0440\u0435\u043d\u0446-\u0437\u0430\u043b\u043e\u0432 \u0432\u043c\u0435\u0441\u0442\u0438\u043c\u043e\u0441\u0442\u044c\u044e \u0434\u043e 450 \u0433\u043e\u0441\u0442\u0435\u0439. &#13;<br \/>\n\u0414\u043e\u0441\u0442\u0443\u043f\u043d\u044b \u0441\u043c\u0435\u0436\u043d\u044b\u0435 \u043d\u043e\u043c\u0435\u0440\u0430.&#13;<br \/>\nWi-Fi \u0438\u043d\u0442\u0435\u0440\u043d\u0435\u0442 \u043a\u0440\u0443\u0433\u043b\u043e\u0441\u0443\u0442\u043e\u0447\u043d\u043e \u0434\u043e\u0441\u0442\u0443\u043f\u0435\u043d \u0432\u043e \u0432\u0441\u0435\u0445 \u0437\u043e\u043d\u0430\u0445 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0433\u043e \u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u044f \u043e\u0442\u0435\u043b\u044f \u0438 \u0432 \u043d\u043e\u043c\u0435\u0440\u0430\u0445, \u0438 \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u043e\u043b\u043d\u043e\u0441\u0442\u044c\u044e \u0431\u0435\u0441\u043f\u043b\u0430\u0442\u043d\u044b\u043c<\/p>\n","parking":"<p>\u0427\u0430\u0441\u0442\u043d\u0430\u044f \u043f\u0430\u0440\u043a\u043e\u0432\u043a\u0430 \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u0431\u0435\u0437 \u043f\u0440\u0435\u0434\u0432\u0430\u0440\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0433\u043e \u0431\u0440\u043e\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u043d\u0430 \u0442\u0435\u0440\u0440\u0438\u0442\u043e\u0440\u0438\u0438 \u0432\u0441\u0435\u0433\u043e \u043e\u0442\u0435\u043b\u044f \u043f\u043e \u0446\u0435\u043d\u0435, \u043d\u0430\u0447\u0438\u043d\u0430\u044f \u043e\u0442 9 \u0415\u0412\u0420\u041e \u0432 \u0434\u0435\u043d\u044c . \u041e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u0430\u044f \u043f\u0430\u0440\u043a\u043e\u0432\u043a\u0430 \u0440\u044f\u0434\u043e\u043c \u0441 \u043e\u0442\u0435\u043b\u0435\u043c, \u043d\u0435 \u0431\u0440\u043e\u043d\u0438\u0440\u0443\u0435\u0442\u0441\u044f (\u043f\u043b\u0430\u0442\u043d\u0430\u044f).<\/p>\n","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.681229","longitude":"9.675441","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Starhotels Cristallo Palace","registered_office":"","iu_addr_streetnumber":"via betty ambiveri, 35","iu_addr_postalcode":"24126","iu_addr_city":"","iu_addr_province":"","iu_phone":"+39 035311211","iu_cell":"","iu_website":"http:\/\/www.starhotels.com\/it\/i-nostri-hotel\/cristallo-palace-bergamo\/","iu_email":"cristallo.bg@starhotels.it","iu_vat":"03360930154","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"4","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"4468","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"safe","label":"safe"},{"value":"night_porter","label":"Portiere notturno"},{"value":"restaurant","label":"Ristorante"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"},{"value":"diners","label":"Diners Club"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto\/182949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto\/182949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/media\/161291"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/media?parent=182949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/categories?post=182949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/tags?post=182949"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/aggr?post=182949"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/area?post=182949"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/kind?post=182949"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/zona?post=182949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}