{"id":183057,"date":"2025-04-18T13:24:39","date_gmt":"2025-04-18T11:24:39","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/albergo-alpino\/"},"modified":"2025-04-18T17:06:10","modified_gmt":"2025-04-18T15:06:10","slug":"albergo-alpino","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/","title":{"rendered":"Albergo Alpino"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":163513,"template":"","categories":[1005],"tags":[],"aggr":[],"area":[],"kind":[18728],"zona":[],"class_list":["post-183057","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-1005","kind-strutturaricettiva-ru"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Albergo Alpino","hero_text":"","slides":[{"image":{"ID":163513,"id":163513,"title":"177229f551d66a195407a4975cf86a12_db3819dc","filename":"177229f551d66a195407a4975cf86a12_db3819dc.jpg","filesize":255675,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/177229f551d66a195407a4975cf86a12_db3819dc-2\/","alt":"","author":"0","description":"","caption":"","name":"177229f551d66a195407a4975cf86a12_db3819dc-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:01","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/177229f551d66a195407a4975cf86a12_db3819dc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163520,"id":163520,"title":"faac674d2a9783a59201607930c124c9_fc208432","filename":"faac674d2a9783a59201607930c124c9_fc208432.jpg","filesize":153563,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/faac674d2a9783a59201607930c124c9_fc208432-2\/","alt":"","author":"0","description":"","caption":"","name":"faac674d2a9783a59201607930c124c9_fc208432-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:02","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faac674d2a9783a59201607930c124c9_fc208432.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163527,"id":163527,"title":"e2806f987d1a404c513ed7af98b7886d_80b2649a","filename":"e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","filesize":150446,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/e2806f987d1a404c513ed7af98b7886d_80b2649a-2\/","alt":"","author":"0","description":"","caption":"","name":"e2806f987d1a404c513ed7af98b7886d_80b2649a-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:02","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2806f987d1a404c513ed7af98b7886d_80b2649a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163534,"id":163534,"title":"11447046c24b5de532d50779d97bbe22_8cea5a05","filename":"11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","filesize":187632,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/11447046c24b5de532d50779d97bbe22_8cea5a05-2\/","alt":"","author":"0","description":"","caption":"","name":"11447046c24b5de532d50779d97bbe22_8cea5a05-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:03","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/11447046c24b5de532d50779d97bbe22_8cea5a05.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163541,"id":163541,"title":"7a72182c25ce7d13284904d2ec43e7e1_9be61cbb","filename":"7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","filesize":275572,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb-2\/","alt":"","author":"0","description":"","caption":"","name":"7a72182c25ce7d13284904d2ec43e7e1_9be61cbb-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:04","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7a72182c25ce7d13284904d2ec43e7e1_9be61cbb.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163548,"id":163548,"title":"9037b8f428d87639def88c9529cebd93_6f003781","filename":"9037b8f428d87639def88c9529cebd93_6f003781.jpg","filesize":239397,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/9037b8f428d87639def88c9529cebd93_6f003781-2\/","alt":"","author":"0","description":"","caption":"","name":"9037b8f428d87639def88c9529cebd93_6f003781-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:05","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":865,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781-300x196.jpg","medium-width":300,"medium-height":196,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781-768x502.jpg","medium_large-width":768,"medium_large-height":502,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","large-width":865,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","1536x1536-width":865,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","2048x2048-width":865,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":196,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":261,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9037b8f428d87639def88c9529cebd93_6f003781.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":392}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163555,"id":163555,"title":"969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12","filename":"969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","filesize":205462,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12-2\/","alt":"","author":"0","description":"","caption":"","name":"969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:06","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/969c65bd0e9e47becaa3a6ca8c7c0947_b3ee8a12.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163562,"id":163562,"title":"252027474fbe355b4803d8bdba919944_7e4ea9c9","filename":"252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","filesize":187117,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/252027474fbe355b4803d8bdba919944_7e4ea9c9-2\/","alt":"","author":"0","description":"","caption":"","name":"252027474fbe355b4803d8bdba919944_7e4ea9c9-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:07","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","large-width":847,"large-height":565,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","1536x1536-width":847,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","2048x2048-width":847,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/252027474fbe355b4803d8bdba919944_7e4ea9c9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163569,"id":163569,"title":"a78ad405f573d5e90ecb733804a2dab0_9f2170e7","filename":"a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","filesize":338667,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","link":"https:\/\/visit.valueservice.cloud\/ru\/oggetto\/albergo-alpino\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7-2\/","alt":"","author":"0","description":"","caption":"","name":"a78ad405f573d5e90ecb733804a2dab0_9f2170e7-2","status":"inherit","uploaded_to":183057,"date":"2025-04-18 08:43:08","modified":"2025-04-18 15:06:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7-300x141.jpg","medium-width":300,"medium-height":141,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7-768x362.jpg","medium_large-width":768,"medium_large-height":362,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7-1024x482.jpg","large-width":1024,"large-height":482,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","1536x1536-width":1200,"1536x1536-height":565,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","2048x2048-width":1200,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":141,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":188,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a78ad405f573d5e90ecb733804a2dab0_9f2170e7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":283}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.929124","longitude":"10.097074","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Albergo Alpino SAS","registered_office":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24020","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 0346 31103","iu_cell":"3289847800","iu_website":"http:\/\/www.hotelalpinopresolana.com","iu_email":"info@hotelalpinopresolana.com","iu_vat":"02619260165","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"3","iu_rooms":"18","iu_beds":"36","id_madeep":"","id_visit_manza":"7309","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"safe","label":"safe"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"restaurant","label":"Ristorante"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto\/183057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/oggetto\/183057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/media\/163513"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/media?parent=183057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/categories?post=183057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/tags?post=183057"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/aggr?post=183057"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/area?post=183057"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/kind?post=183057"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/ru\/wp-json\/wp\/v2\/zona?post=183057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}